{"id":499,"date":"2019-04-09T15:49:01","date_gmt":"2019-04-09T15:49:01","guid":{"rendered":"https:\/\/master.greenpeace.ch\/?page_id=499"},"modified":"2025-08-04T11:05:53","modified_gmt":"2025-08-04T09:05:53","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/www.greenpeace.ch\/de\/kontakt\/","title":{"rendered":"Kontaktinformationen"},"content":{"rendered":"\n\n<div class=\"wp-block-group alignfull is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-media-text alignfull has-media-on-the-right is-stacked-on-mobile is-pattern-p4-page-header is-style-parallax\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<h1 class=\"wp-block-heading has-white-background-color has-background\">\n                            Kontakt\n                        <\/h1>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/e8559e3c-gp0stskla_high_res.jpg\" alt=\"\" sizes=\"(min-width: 601px) 50vw, 100vw\" srcset=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/e8559e3c-gp0stskla_high_res-e1558701690877.jpg 5731w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/e8559e3c-gp0stskla_high_res-e1558701690877-300x130.jpg 300w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/e8559e3c-gp0stskla_high_res-e1558701690877-768x334.jpg 768w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/e8559e3c-gp0stskla_high_res-e1558701690877-1024x445.jpg 1024w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/e8559e3c-gp0stskla_high_res-e1558701690877-2048x890.jpg 2048w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/e8559e3c-gp0stskla_high_res-e1558701690877-510x222.jpg 510w\" class=\"wp-image-2175 size-full\"\/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Gerne beantworten wir deine Fragen und nehmen Anregungen zu unseren Kampagnen entgegen. Wir beraten dich zu all unseren Angeboten und stehen dir mit Antworten zu deiner Mitgliedschaft sowie Spenden zur Verf\u00fcgung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hauptsitz Z\u00fcrich<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><strong>Lieferanteneingang \/ Postadresse Pakete<\/strong><\/strong><br>Greenpeace Schweiz<br>Badenerstrasse 171<br>8003 Z\u00fcrich<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Besuchereingang<\/strong><br>Via grosser Aussentreppe an Ecke Kalkbreite-\/Badenerstrasse.<br>Glast\u00fcre auf der rechten Seite mit der Aufschrift \u00abGreenpeace\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Postadresse Briefe<\/strong><br>Greenpeace Schweiz<br>Badenerstrasse 171<br>Postfach<br>8036 Z\u00fcrich<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Telefonnummer<\/strong><br>+41 44 447 41 41<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>E-Mail<\/strong><br><a href=\"mailto:schweiz@greenpeace.org\">schweiz@greenpeace.org<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00d6ffnungszeiten<br><\/strong>Montag bis Donnerstag 9.00\u201312.00 &amp; 14.00\u201316.30<br>Freitags geschlossen<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-background-1 is-layout-flow wp-block-column-is-layout-flow\"><script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_236' ><div id='gf_236' class='gform_anchor' tabindex='-1'><\/div>\n                        <div class='gform_heading'>\n\t\t\t\t\t\t\t<p class='gform_required_legend'>&quot;<span class=\"gfield_required gfield_required_asterisk\">*<\/span>&quot; kennzeichnet Pflichtfelder <\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_236' id='gform_236'  action='\/de\/wp-json\/wp\/v2\/pages\/499#gf_236' data-formid='236' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_236' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_236_9\" class=\"gfield gfield--type-html gfield--input-type-html gfield--width-full gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2>Kontaktformular<\/h2><\/div><div id=\"field_236_1\" class=\"gfield gfield--type-select gfield--input-type-select gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_236_1'>Thema<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_1' id='input_236_1' class='large gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='Sonstiges' >Sonstiges<\/option><option value='Adress\u00e4nderung' >Adress\u00e4nderung<\/option><option value='K\u00fcndigung' >K\u00fcndigung<\/option><\/select><\/div><\/div><div id=\"field_236_2\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_236_2'>Vorname<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_2' id='input_236_2' type='text' value='' class='large' maxlength='120'    aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_236_4\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_236_4'>Nachname<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_4' id='input_236_4' type='text' value='' class='large' maxlength='120'    aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><fieldset id=\"field_236_5\" class=\"gfield gfield--type-address gfield--input-type-address gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Addresse<\/legend>    \n                    <div class='ginput_complex ginput_container has_street has_city has_zip ginput_container_address gform-grid-row' id='input_236_5' >\n                         <span class='ginput_full address_line_1 ginput_address_line_1 gform-grid-col' id='input_236_5_1_container' >\n                                        <input type='text' name='input_5.1' id='input_236_5_1' value=''    aria-required='false'    \/>\n                                        <label for='input_236_5_1' id='input_236_5_1_label' class='gform-field-label gform-field-label--type-sub '>Adresse<\/label>\n                                    <\/span><span class='ginput_left address_zip ginput_address_zip gform-grid-col' id='input_236_5_5_container' >\n                                    <input type='text' name='input_5.5' id='input_236_5_5' value=''    aria-required='false'    \/>\n                                    <label for='input_236_5_5' id='input_236_5_5_label' class='gform-field-label gform-field-label--type-sub '>PLZ<\/label>\n                                <\/span><span class='ginput_right address_city ginput_address_city gform-grid-col' id='input_236_5_3_container' >\n                                    <input type='text' name='input_5.3' id='input_236_5_3' value=''    aria-required='false'    \/>\n                                    <label for='input_236_5_3' id='input_236_5_3_label' class='gform-field-label gform-field-label--type-sub '>Ort<\/label>\n                                 <\/span><input type='hidden' class='gform_hidden' name='input_5.4' id='input_236_5_4' value=''\/><input type='hidden' class='gform_hidden' name='input_5.6' id='input_236_5_6' value='' \/>\n                    <div class='gf_clear gf_clear_complex'><\/div>\n                <\/div><\/fieldset><div id=\"field_236_6\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_236_6'>Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_6' id='input_236_6' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_236_7\" class=\"gfield gfield--type-textarea gfield--input-type-textarea gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_236_7'>Nachricht<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_7' id='input_236_7' class='textarea large'   maxlength='2000'   aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><div id=\"field_236_10\" class=\"gfield gfield--type-turnstile gfield--input-type-turnstile gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_turnstile'><div class=\"cf-turnstile\" id=\"cf-turnstile_236\" data-js-turnstile data-response-field-name=\"cf-turnstile-response_236\" data-theme=\"light\" data-size=\"\" data-sitekey=\"0x4AAAAAAAIjyfgzS29xh918\"><\/div><\/div><\/div><div id=\"field_236_8\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_8' id='input_236_8' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='contact' \/><\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_236' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Submit'  \/> <input type='hidden' name='gform_ajax' value='form_id=236&amp;title=&amp;description=&amp;tabindex=0&amp;theme=gravity-theme&amp;styles={&quot;inputPrimaryColor&quot;:&quot;#204ce5&quot;}&amp;hash=38a0a2c2d371bfd44a7b0d608d73e966' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_236' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_236' id='gform_theme_236' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_236' id='gform_style_settings_236' value='{&quot;inputPrimaryColor&quot;:&quot;#204ce5&quot;}' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_236' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='236' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='CHF' value='KvACapMCJh3RsWbqQwvccJp1L+yquVlk5PVRKYUWy5cbgoutpSK6kOZdnhjp8vPigqUxDI7gs7FS9OaVsZeLl9dqU++TkQXlFuQkD8eNAsWkrIg=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_236' value='WyJbXSIsIjAyYTRhYjNlYmQ4MDQ2NmNkNDhhYmQ4MGQwMjNjMDZjIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_236' id='gform_target_page_number_236' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_236' id='gform_source_page_number_236' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"189\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_236' id='gform_ajax_frame_236' title='This iframe contains the logic required to handle Ajax powered Gravity Forms.'><\/iframe>\n\t\t                <script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 236, 'https:\/\/www.greenpeace.ch\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_236').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_236');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_236').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_236').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_236').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_236').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_236').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_236').val();gformInitSpinner( 236, 'https:\/\/www.greenpeace.ch\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [236, current_page]);window['gf_submitting_236'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_236').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_236').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [236]);window['gf_submitting_236'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_236').text());}else{jQuery('#gform_236').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"236\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_236\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_236\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_236\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 236, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n<\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading is-style-underline\">Spendenkonto<\/h2>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Online<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Spende mit Twint, Postcard, Kreditkarte oder PayPal.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.greenpeace.ch\/de\/act\/spenden\/\">Spenden<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Konto<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>IBAN<\/strong><br>CH07 0900 0000 8000 6222 8<br>Greenpeace Schweiz<br>Badenerstrasse 171<br>8003 Z\u00fcrich<\/p>\n<\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading is-style-underline\">H\u00e4ufige Fragen<\/h2>\n\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Spenden \/ Mitgliedschaft<\/h3>\n\n\n\n<section class=\"block accordion-block wp-block-planet4-blocks-accordion\"><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Wof\u00fcr wird meine Spende eingesetzt?\">Wof\u00fcr wird meine Spende eingesetzt?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Mit deinem Mitgliederbeitrag oder einer allgemeinen Spende unterst\u00fctzt du unsere Arbeit in den Kernkampagnenthemen Klima, Zero Waste, Landwirtschaft, Meer, Wald, Arktis und Antarktis. Deine Spende ist die Basis unserer Unabh\u00e4ngigkeit. Sie erm\u00f6glicht uns, unsere Mittel jederzeit dort einzusetzen, wo sie am dringendsten gebraucht werden und am meisten Nutzen bringen.<br>Detaillierte Informationen \u00fcber die Mittel, die in unsere Kampagnen geflossen sind, findest du in unserem Jahresbericht.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Wie hoch ist der j\u00e4hrliche Mitgliederbeitrag?\">Wie hoch ist der j\u00e4hrliche Mitgliederbeitrag?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Die Mitgliedschaft (inkl. Greenpeace-Magazin) ist ab CHF 84 pro Jahr erh\u00e4ltlich. Selbstverst\u00e4ndlich freuen wir uns sehr, wenn du unsere Kampagnenarbeit auch mit einem h\u00f6heren Betrag unterst\u00fctzt.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Warum geben die Dialoger auf der Strasse keine Einzahlungsscheine ab, sondern fragen nach der Bank- oder Postkontoverbindung?\">Warum geben die Dialoger auf der Strasse keine Einzahlungsscheine ab, sondern fragen nach der Bank- oder Postkontoverbindung?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Unterst\u00fctzungen, welche durch einen automatischen \u00dcberweisungsauftrag (LSV) ausgef\u00fchrt werden, reduzieren den Papierverbrauch, sparen Portokosten und generieren f\u00fcr die Empf\u00e4nger:in keinerlei Spesen (weder administrative noch finanzielle), da die Verbuchung automatisch eingelesen werden kann. Kurz gesagt: Deine Spende kommt noch effektiver der Umweltarbeit zugute und erm\u00f6glicht es uns, unsere Kampagnenarbeit deutlich besser vorausplanen zu k\u00f6nnen. Der Auftrag kann von dir jederzeit mit einem kurzen Anruf fristlos widerrufen werden.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Gibt es spezielle Partner- und Familienmitgliedschaften?\">Gibt es spezielle Partner- und Familienmitgliedschaften?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Wir bieten Jugendmitgliedschaften (bis 18 Jahre) f\u00fcr CHF 25 pro Jahr. Spezielle Familien- oder Partnermitgliedschaften bieten wir nicht an, schreiben dich aber gerne zusammen als Familie oder Paar (ab CHF 84 pro Jahr) an und freuen uns sehr, wenn du unsere Kampagnenarbeit auch mit einem h\u00f6heren Betrag unterst\u00fctzt.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Wie funktioniert eine Geschenkmitgliedschaft?\">Wie funktioniert eine Geschenkmitgliedschaft?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Mit einer Geschenkmitgliedschaft schenkst du deinen Lieben etwas Sinnvolles und tust etwas Gutes f\u00fcr die Umwelt. Die beschenkte Person gewinnt als Greenpeace-Mitglied Einblick in die Umwelt- und Klimaschutzarbeit der Organisation. Dreimal j\u00e4hrlich erh\u00e4lt sie das Mitgliedermagazin mit Reportagen, Hintergrundberichten und Informationen zu den Kampagnen. F\u00fclle dazu einfach das Formular auf unserer Website aus\u00a0<a href=\"https:\/\/www.greenpeace.ch\/de\/handeln\/spenden\/geschenkmitgliedschaft\/\">(www.greenpeace.ch\/geschenk<\/a>). Beim Abschluss einer Geschenkmitgliedschaft erh\u00e4ltst du als Willkommensgeschenk einen 10-Franken-Gutschein f\u00fcr unseren Webshop.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Wann wird mir die Spendenbest\u00e4tigung f\u00fcr die Steuerbeh\u00f6rde zugestellt?\">Wann wird mir die Spendenbest\u00e4tigung f\u00fcr die Steuerbeh\u00f6rde zugestellt?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Die Spendenbest\u00e4tigung stellen wir dir automatisch im Januar des darauffolgenden Jahres zu.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Ich habe meine Mitgliedschaft im Sommer abgeschlossen. Wieso erhalte ich bereits im Januar wieder eine Rechnung?\">Ich habe meine Mitgliedschaft im Sommer abgeschlossen. Wieso erhalte ich bereits im Januar wieder eine Rechnung?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Alle Mitgliederbeitr\u00e4ge bei Greenpeace gelten grunds\u00e4tzlich pro Kalenderjahr bzw. von Januar bis Dezember eines Jahres. Dies hat einen rein praktischen Grund. Es ist in unserer Datenbank bisher nicht m\u00f6glich, eine Mitgliedschaft zu terminieren. Deshalb kommt es vor, dass bei einem Eintritt im Juni im darauffolgenden Januar ein Brief mit der Bitte um Erneuerung der Mitgliedschaft eintrifft.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Ich erhalte zu viel oder doppelt Post. Was soll ich dagegen tun?\">Ich erhalte zu viel oder doppelt Post. Was soll ich dagegen tun?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Gerne passen wir unsere Versandliste deinen Bed\u00fcrfnissen an. Deinen Wunsch nach weniger Post kannst du uns per E-Mail unter <a href=\"mailto:schweiz@greenpeace.org\">schweiz@greenpeace.org<\/a>\u00a0oder per Telefon unter 044 447 41 41 mitteilen.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Ich habe eine neue Adresse.\">Ich habe eine neue Adresse.<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Bitte sende uns eine Mitteilung an <a href=\"mailto:schweiz@greenpeace.org\">schweiz@greenpeace.org<\/a> mit Angabe deiner bisherigen Adresse und, falls m\u00f6glich, deiner Mitgliedernummer.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Braucht es ein neues LSV-Formular, wenn sich mein Konto ge\u00e4ndert hat?\">Braucht es ein neues LSV-Formular, wenn sich mein Konto ge\u00e4ndert hat?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Ja, du kannst dieses <a href=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2024\/06\/c2b89381-lsv_de_web_2024.pdf\">hier<\/a> herunterladen. Bitte sende uns das ausgef\u00fcllte und unterschriebene Formular zur\u00fcck.<br>M\u00f6chtest du die H\u00f6he deines Beitrags bei gleichbleibendem Konto \u00e4ndern, reicht eine Erlaubnis deinerseits telefonisch unter 044 447 41 41 oder per E-Mail an <a href=\"mailto:schweiz@greenpeace.org\">schweiz@greenpeace.org<\/a>.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Ich m\u00f6chte meine Mitgliedschaft k\u00fcnden.\">Ich m\u00f6chte meine Mitgliedschaft k\u00fcnden.<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Bitte ruf unseren Supporter Service unter 044 447 41 41 an, damit wir dein Anliegen umgehend bearbeiten k\u00f6nnen.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Wie kann ich mich vom Newsletter abmelden?\">Wie kann ich mich vom Newsletter abmelden?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Du kannst dich durch Anklicken des Abmelde-Links ganz unten im E-Newsletter jederzeit vom Verteiler abmelden.<\/p><\/div><\/div><\/section>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Allgemein<\/h3>\n\n\n\n<section class=\"block accordion-block wp-block-planet4-blocks-accordion\"><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Was ist das Leitbild von Greenpeace?\">Was ist das Leitbild von Greenpeace?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Greenpeace ist eine unabh\u00e4ngige, internationale Umweltorganisation, die sich seit 1971 weltweit f\u00fcr eine \u00f6kologische, soziale und gerechte Gegenwart und Zukunft einsetzt. In 55 L\u00e4ndern arbeiten wir f\u00fcr den Erhalt der genetischen Vielfalt, des Klimas und f\u00fcr den Schutz von W\u00e4ldern und Meeren und vor atomarer und chemischer Verseuchung.<br>Ausf\u00fchrliche Informationen \u00fcber Greenpeace und ihre Geschichte findest du <a href=\"https:\/\/www.greenpeace.ch\/de\/ueber-uns\/#WeitereInfos\">hier<\/a>.<br>Angaben \u00fcber die Anzahl unserer Unterst\u00fctzer:innen und die Finanzen allgemein findest du jeweils in unserem Jahresbericht.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Wo finde ich die Adresse eines Greenpeace-B\u00fcros in meiner N\u00e4he?\">Wo finde ich die Adresse eines Greenpeace-B\u00fcros in meiner N\u00e4he?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Du findest die \u00dcbersicht \u00fcber alle Greenpeace-B\u00fcros weltweit auf <a href=\"https:\/\/www.greenpeace.org\/global\/\">https:\/\/www.greenpeace.org\/global\/<\/a>.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Wo gibt es in der Schweiz Greenpeace-Produkte zu kaufen?\">Wo gibt es in der Schweiz Greenpeace-Produkte zu kaufen?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Du findest eine kleine Auswahl an Greenpeace-Produkten in unserem Webshop: <a href=\"https:\/\/shop.greenpeace.ch\/\">shop.greenpeace.ch<\/a>.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Ich m\u00f6chte eine schriftliche Arbeit \u00fcber Greenpeace machen. Wo finde ich Unterlagen und wen kann ich dazu interviewen?\">Ich m\u00f6chte eine schriftliche Arbeit \u00fcber Greenpeace machen. Wo finde ich Unterlagen und wen kann ich dazu interviewen?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Auf unserer Website findest du Unterlagen zu Greenpeace allgemein und zu allen Themen, zu denen Greenpeace Kampagnen f\u00fchrt. Publikationen kannst du <a rel=\"noreferrer noopener\" href=\"https:\/\/www.greenpeace.ch\/de\/publikation\/\" target=\"_blank\">hier<\/a> downloaden. Ansonsten empfehlen wir dir, die Suchfunktion zu nutzen.<br>Aus Kapazit\u00e4tsgr\u00fcnden beantworten wir Interviews von max. f\u00fcnf Fragen ausschliesslich per E-Mail, vielen Dank f\u00fcr dein Verst\u00e4ndnis.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Wie kann ich bei Greenpeace mitmachen?\">Wie kann ich bei Greenpeace mitmachen?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Auf unserer Website unter der Rubrik \u00ab<a rel=\"noreferrer noopener\" href=\"https:\/\/www.greenpeace.ch\/de\/handeln\/freiwillige\/\" target=\"_blank\">Mitmachen<\/a>\u00bb findest du verschiedene M\u00f6glichkeiten, dich selber aktiv einzusetzen \u2013 zum Beispiel in einer Regionalgruppe.<\/p><\/div><\/div><div class=\"accordion-content\"><div class=\"accordion-headline\" name=\"Ich habe im Internet Bilder von Tierqu\u00e4lerei gesehen. Kann Greenpeace etwas dagegen tun?\">Ich habe im Internet Bilder von Tierqu\u00e4lerei gesehen. Kann Greenpeace etwas dagegen tun?<\/div><div class=\"panel panel-hidden\"><p class=\"accordion-text\">Greenpeace unterst\u00fctzt alle Initiativen im Bereich Tierschutz, arbeitet jedoch selber nicht zum Thema. Greenpeace ist eine Umweltschutzorganisation. Wir konzentrieren uns auf den Artenschutz f\u00fcr bedrohte Meerestiere wie Wale und Delfine, engagieren uns gegen den Handel mit bedrohten Arten und setzen uns f\u00fcr den Schutz der Meere und W\u00e4lder ein. Eine Beschr\u00e4nkung auf gewisse Themen ist notwendig, damit wir unsere Mittel wirksam einsetzen k\u00f6nnen. Bitte wende dich mit deinem Anliegen direkt an die Tierschutzorganisationen.<\/p><\/div><\/div><\/section>\n\n\n\n<figure class=\"wp-block-image caption-style-medium caption-alignment-center\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" title=\"Two RHIBs Prepare for a Dive in South Australia\" src=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/575fc5ca-gp0stswn7_high_res-1024x684.jpg\" alt=\"\" class=\"wp-image-2802\" srcset=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/575fc5ca-gp0stswn7_high_res-1024x684.jpg 1024w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/575fc5ca-gp0stswn7_high_res-300x200.jpg 300w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/575fc5ca-gp0stswn7_high_res-768x513.jpg 768w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/575fc5ca-gp0stswn7_high_res-2046x1366.jpg 2046w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/575fc5ca-gp0stswn7_high_res-510x340.jpg 510w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kontaktiere uns mit Fragen und Anregungen zu unseren Kampagnen. Wir beraten dich zu all unseren Angeboten und stehen dir mit Antworten zu deiner Mitgliedschaft sowie Spenden zur Verf\u00fcgung.<\/p>\n","protected":false},"author":25,"featured_media":2175,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_planet4_optimize_post_is_variant":false,"_planet4_optimize_experiment_name":"","_planet4_optimize_variant_name":"","ep_exclude_from_search":false,"p4_hide_page_title_checkbox":"on","p4_title":"","p4_subtitle":"","p4_description":"","background_image_id":"","background_image":"","p4_button_title":"","p4_button_link":"","p4_button_link_checkbox":"","p4_og_title":"","p4_og_description":"Kontaktiere uns mit Fragen und Anregungen zu unseren Kampagnen. Wir beraten dich zu all unseren Angeboten und stehen dir mit Antworten zu deiner Mitgliedschaft sowie Spenden zur Verf\u00fcgung.","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"not set","p4_local_project":"not set","p4_basket_name":"not set","p4_department":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-499","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/pages\/499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/comments?post=499"}],"version-history":[{"count":5,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/pages\/499\/revisions"}],"predecessor-version":[{"id":122550,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/pages\/499\/revisions\/122550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/media\/2175"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/media?parent=499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/categories?post=499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/tags?post=499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}