{"id":101002,"date":"2023-08-20T08:01:00","date_gmt":"2023-08-20T06:01:00","guid":{"rendered":"https:\/\/www.greenpeace.ch\/?p=101002"},"modified":"2023-08-22T12:49:14","modified_gmt":"2023-08-22T10:49:14","slug":"parlament-energiesicherheit-studie","status":"publish","type":"post","link":"https:\/\/www.greenpeace.ch\/de\/medienmitteilung\/101002\/parlament-energiesicherheit-studie\/","title":{"rendered":"Klima: Seit 25 Jahren blockiert die SVP im Parlament alle Bem\u00fchungen um Energiesicherheit"},"content":{"rendered":"\n<p><strong>Eine\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/mail.greenpeace.ch\/d\/d.pdf?p00khw2h7776li0qd0000lh0000000000000gcf0qhhrrw0pcm6lvuii000dy6000000ld63hfe\" target=\"_blank\">neue Studie im Auftrag von Greenpeace Schweiz<\/a>\u00a0analysiert das Abstimmungsverhalten der gr\u00f6ssten Parteien im Nationalrat zu Energie- und Klimafragen seit 1998. Fazit: W\u00e4hrend Mitteparteien und das rot-gr\u00fcne Lager Massnahmen zur F\u00f6rderung der Energiewende unterst\u00fctzt haben, war dies bei den Rechtsparteien nur ausnahmsweise der Fall. Die SVP hat alle Massnahmen abgelehnt, welche die Energiesicherheit des Landes durch erneuerbare Energien verbessern.<\/strong><br><br>19 Abstimmungen im Nationalrat zwischen 1998 und 2020 werden in der\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/mail.greenpeace.ch\/d\/d.pdf?p00khw2h7776li0qd0000lh0000000000000gcf0qhhrrw0pcm6lvuii000dy6000000ld63hfe\" target=\"_blank\">heute ver\u00f6ffentlichten Studie von Politimpuls<\/a>\u00a0ber\u00fccksichtigt. Dabei stimmte die SVP durchg\u00e4ngig gegen die St\u00e4rkung der Energieeffizienz, den Ausbau erneuerbarer Energien und gegen Klimaschutzmassnahmen. Die Reduktion der Abh\u00e4ngigkeit von Importen und die Entwicklung einer einheimischen Energieproduktion, also die explizite F\u00f6rderung der Sicherheit und Unabh\u00e4ngigkeit des Schweizer Energiesystems, fand bei den Nationalr\u00e4t:innen der SVP kaum Unterst\u00fctzung.<br><br>&#8220;Die SVP behauptet bei jeder sich bietenden Gelegenheit, sie wolle die Schweiz vor einer drohenden Energieknappheit sch\u00fctzen&#8221;, erkl\u00e4rt Georg Klingler, Energieexperte bei Greenpeace. &#8220;Die Fakten zeigen etwas ganz anderes: Die Partei hat alles getan, um die Erh\u00f6hung der Produktion von Strom aus erneuerbaren Energien oder die Umsetzung von ehrgeizigen Massnahmen zur Energieeffizienz zu sabotieren. Statt ein unabh\u00e4ngiges und sicheres Energiemodell mit erneuerbaren Energien anzustreben, bremst sie die Entwicklung einer einheimischen Stromproduktion seit Jahrzehnten aus. Sie ist direkt mitverantwortlich, dass die Schweiz ihre enorme Abh\u00e4ngigkeit vom Import fossiler und atomarer Energietr\u00e4ger aus unsicheren L\u00e4ndern nicht wesentlich verringern konnte und heute bei der einheimischen Stromproduktion mit Sonne und Wind im Vergleich zu anderen L\u00e4ndern schlecht dasteht. &#8221;\u00a0<\/p>\n\n<h4 class=\"wp-block-heading\"><br><strong>Linke und Mitteparteien sind sich einig<\/strong><\/h4>\n\n<p><br>Die FDP hat lange Zeit eine \u00e4hnliche Haltung wie die SVP eingenommen. Erst in den letzten drei ber\u00fccksichtigten Abstimmungen hat sie sich deutlich zugunsten der Energiesicherheit und des Klimaschutzes positioniert. Dabei handelte es sich um die Abstimmungen im Zusammenhang mit der Totalrevision des CO2-Gesetzes f\u00fcr die Zeit nach 2020. &#8220;Die grosse Mehrheit der FDP-Nationalr\u00e4t:innen hat die Kernpunkte der Vorlage damals unterst\u00fctzt&#8221;, sagt Georg Klingler. &#8220;Die Zukunft wird zeigen, ob diese Neuorientierung Bestand hat. Ist dies der Fall, k\u00f6nnte sie entscheidend sein, um die Klimaziele unseres Landes zu erreichen.&#8221;&nbsp;<br><br>Die Gr\u00fcnen, die Gr\u00fcnliberalen, die SP, die EVP und die BDP haben alle mehrheitlich f\u00fcr den Klimaschutz und die Energiesicherheit gestimmt. In den ausgew\u00e4hlten Fragen ist das Abstimmungsverhalten von links und in der Mitte positionierten Parteien fast deckungsgleich. Nur die ehemalige CVP tanzte dabei aus der Reihe. Sie war jeweils entscheidend, auf welche Seite die Mehrheit kippte. Das liess sich in 13 der 19 von der Studie ber\u00fccksichtigten Abstimmungen beobachten.&nbsp;<\/p>\n\n<p>Die 19 Abstimmungen im Nationalrat bezogen sich auf die elf relevantesten Vorlagen f\u00fcr die Energiesicherheit und den Klimaschutz, die zwischen 1998 und 2020 im Nationalrat durchgef\u00fchrt wurden. Die Auswahl erlaubt damit ein umfassendes Bild der Debatten rund um Energiesicherheit und KIimaschutz der letzten 20 Jahre.&nbsp;<\/p>\n\n<h4 class=\"wp-block-heading\"><strong>Weiterf\u00fchrende Informationen:<\/strong><\/h4>\n\n<p>Die Studie &#8220;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/08\/804fa458-d-2023-08-07-analyse-klimaschutz-und-energiesicherheit-politimpuls.pdf\" target=\"_blank\">Welche Parteien setzen sich f\u00fcr Klimaschutz und Energiesicherheit ein?<\/a>&#8220;, von <a href=\"https:\/\/politimpuls.ch\" target=\"_blank\" rel=\"noreferrer noopener\">politimpuls<\/a> im Auftrag von Greenpeace Schweiz, August 2023<\/p>\n\n<h4 class=\"wp-block-heading\"><strong>Kontakt:&nbsp;<\/strong><\/h4>\n\n<p>Georg Klingler, Klima- und Energieexperte Greenpeace Schweiz, +41 79 785 07 38, georg.klingler@greenpeace.org<br>Daniel Hitzig, Mediensprecher Greenpeace Suisse, +41 79 238 39 31,<br>daniel.hitzig@greenpeace.org<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine neue Studie im Auftrag von Greenpeace Schweiz analysiert das Abstimmungsverhalten der wichtigsten Parteien im Nationalrat zu Energie- und Klimafragen seit 1998. Insbesondere die SVP hat systematisch alle Massnahmen abgelehnt, welche die Energiesicherheit des Landes durch erneuerbare Energien verbessern.<\/p>\n","protected":false},"author":37,"featured_media":100998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_planet4_optimize_post_is_variant":false,"_planet4_optimize_experiment_name":"","_planet4_optimize_variant_name":"","ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/08\/98921202-gp0stsatl_web_size_with_credit_line.jpg","p4_og_image_id":"100998","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[1],"tags":[36,42,203,50],"p4-page-type":[71],"gpch-article-type":[],"class_list":["post-101002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert","tag-gletscher-initiative","tag-energie","tag-co2-gesetz","tag-klima","p4-page-type-medienmitteilung"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts\/101002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/comments?post=101002"}],"version-history":[{"count":0,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts\/101002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/media\/100998"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/media?parent=101002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/categories?post=101002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/tags?post=101002"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/p4-page-type?post=101002"},{"taxonomy":"gpch-article-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/gpch-article-type?post=101002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}