{"id":14412,"date":"2011-11-16T00:00:00","date_gmt":"2011-11-15T22:00:00","guid":{"rendered":"https:\/\/master.greenpeace.ch\/beitrag\/14412\/der-preis-einer-dose-thunfisch\/"},"modified":"2019-05-30T12:32:57","modified_gmt":"2019-05-30T10:32:57","slug":"der-preis-einer-dose-thunfisch","status":"publish","type":"post","link":"https:\/\/www.greenpeace.ch\/de\/story\/14412\/der-preis-einer-dose-thunfisch\/","title":{"rendered":"Der Preis einer Dose Thunfisch"},"content":{"rendered":"<p><b>Schockierende Film-Aufnahmen eines Augenzeugen belegen, wie durch den Einsatz von so genannten Fischsammlern beim Thunfischfang unz\u00e4hlige Meerestiere sterben &#8211; darunter Wale, Delfine, Haie oder Mantarochen.<\/b><\/p>\n<div>\n<div class=\"events-box middle-box right\">\n<div class=\"frame\">\n        <a class=\"open-img EnlargeImage\" href=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/4e8d479f-4e8d479f-111117-story-meer-tuna.jpg\" title=\"\"><br \/>\n            <img decoding=\"async\" id=\"ctl00_cphContentArea_Property3_ctl00_ctl02_Image1\" class=\"Thumbnail\" src=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2019\/05\/4e8d479f-4e8d479f-111117-story-meer-tuna.jpg\" alt=\"\" style=\"border-width:0px;\"><\/p>\n<p>        <\/a>\n    <\/div>\n<div class=\"events-content no-title\">\n        <span class=\"date\"><\/span><br \/>\n        <strong><\/strong><\/p>\n<p>\n            Die Videoausschnitte des Hubschrauber-Piloten eines Thunfischj\u00e4gers sind nicht f\u00fcr zart besaitete Augen geeignet.\n        <\/p>\n<\/p>\n<\/div>\n<\/div>\n<p>Er hat es nicht mehr ausgehalten: Ein Informant aus der Fischereibranche hat Greenpeace Videoaufnahmen zugespielt, die das kalte, sinnlose Schlachten an Bord eines Thunfischtrawlers zeigen &#8211; und damit die wahren Kosten einer Dose Thunfisch.<\/p>\n<p>\u00abRifffische, Mantarochen, Delphine, Schwertfische, Wale. Alles wurde an Bord gehievt&#8230;\u00bb Der Mann, der dies erz\u00e4hlt, muss anonym bleiben, um seine Existenz nicht zu gef\u00e4hrden. Sein Gesicht wird im Video nicht gezeigt, seine Stimme verzerrt wiedergegeben. Im vergangenen Jahr war er Hubschrauberpilot auf einem koreanischen Ringwadentrawler im Pazifik. Seine Aufgabe war es, Thunfischschw\u00e4rme aufzusp\u00fcren.<\/p>\n<p>Die F\u00e4nger arbeiteten mit Ringwadennetzen und sogenannten Fischsammlern (Fish Aggregation Devices (FADs)). Fischsammler t\u00e4uschen Schutz vor und ziehen so Fische aller Art, aber auch andere Meereslebewesen magisch an. Um die schwimmenden Plattformen herum wimmelt es deshalb von Fischen und anderen Tieren. Das Ringwadennetz wird drumherum gelegt und muss nur zugezogen werden.<\/p>\n<p>\u00abJeden Morgen fragte man sich, was man wohl an diesem Tag fangen w\u00fcrde. Ohne FADs war der Beifang fast null. Mit FADs war er sehr hoch.\u00bb Auch junge Thunfische gehen ins Netz &#8211; zu jung, um sich schon vermehrt zu haben. So werden die sowieso schon bedrohten Best\u00e4nde weiter dezimiert. \u00abZu kleine Fische gingen fast nur beim Fischen mit FADs ins Netz&#8230;\u00bb<\/p>\n<p><strong><span style=\"text-decoration: underline;\">Das Video in voller L\u00e4nge &#8211; Achtung: Nichts f\u00fcr schwache Nerven<\/span><br \/><\/strong><\/p>\n<p><iframe loading=\"lazy\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/6JlKwoUtMk4\" frameborder=\"0\" allowfullscreen=\"\"><\/iframe><\/p>\n<p>Fast 60 Prozent aller gefangenen Thunfische kommen aus dem Pazifik. Die Best\u00e4nde an Grossaugenthun und Gelbflossenthun sind dort bereits \u00fcberfischt. <strong>Greenpeace fordert deshalb dringend ein Verbot der Ringwadenfischerei mit Fischsammlern. Zudem m\u00fcssen die Fangquoten f\u00fcr Thunfisch im West- und Mittelpazifik um die H\u00e4lfte gek\u00fcrzt werden.<\/strong><\/p>\n<p>Mehrere Hersteller von Thunfischprodukten haben bereits zugestimmt, keinen Fisch mehr abzunehmen, der mit FADs gefangen wurde. Darunter sind die grossen britischen Hersteller Princes und <a href=\"http:\/\/www.greenpeace.org\/switzerland\/de\/News_Stories\/Newsblog\/erfolg-in-der-thunfisch-kampagne\/blog\/36151\/\">John West<\/a>.<\/p>\n<p>Dieses Video soll aber auch die KonsumentInnen informieren &#8211; sie haben ein Recht zu  erfahren, was es die Natur kostet, eine Dose mit Thunfisch zu f\u00fcllen. Auch beim t\u00e4glichen Einkauf kann jeder seinen Beitrag leisten, indem man darauf achtet aus welchem Fangebiet und mit welcher Fangmethode der Thunfisch in die Dose kam.<\/p>\n<h4><strong>Fischsammler mit enormen Beifangmengen<\/strong><\/h4>\n<p>Der Grossteil des Dosentunfisches wird heute mit Fischsammlern (engl. FADs &#8211; Fish Aggregation Devices) gefangen. Das sind k\u00fcnstliche schwimmende Objekte, die den angeborenen Instinkt der Schwarmfische ausnutzen, im Schatten von treibenden Gegenst\u00e4nden Schutz zu suchen. Die Ringwade wird dann um die Fischsammler herum ausgebracht. Doch dieses Hilfsmittel f\u00fchrt zu enormen Beifangmengen: Nicht nur Skipjack-Thunfisch wird angelockt, sondern auch andere Thunfischarten oder gef\u00e4hrdete Meerestiere wie Haie, Wale, Rochen und Schildkr\u00f6ten. 2005 wurden \u00fcber 1 Millionen Tonnen Thunfisch, ein Drittel des weltweites Thunfisch-Fanges, und \u00fcber 100.000 Tonnen Beifang mit FADs gefangen.<\/p>\n<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Schockierende Film-Aufnahmen eines Augenzeugen belegen, wie durch den Einsatz von so genannten Fischsammlern beim Thunfischfang unz\u00e4hlige Meerestiere sterben &#8211; darunter Wale, Delfine, Haie oder Mantarochen. Die Videoausschnitte des Hubschrauber-Piloten eines&hellip;<\/p>\n","protected":false},"author":23,"featured_media":14414,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_planet4_optimize_post_is_variant":false,"_planet4_optimize_experiment_name":"","_planet4_optimize_variant_name":"","ep_exclude_from_search":false,"gpch_hide_header_image":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[1],"tags":[],"p4-page-type":[75],"gpch-article-type":[],"class_list":["post-14412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert","p4-page-type-story"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts\/14412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/comments?post=14412"}],"version-history":[{"count":0,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts\/14412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/media\/14414"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/media?parent=14412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/categories?post=14412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/tags?post=14412"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/p4-page-type?post=14412"},{"taxonomy":"gpch-article-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/gpch-article-type?post=14412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}