{"id":6682,"date":"2006-08-30T00:00:00","date_gmt":"2006-08-29T22:00:00","guid":{"rendered":"https:\/\/master.greenpeace.ch\/beitrag\/6682\/alpines-museum-zeigt-gletscher-im-treibhaus\/"},"modified":"2019-05-30T07:35:03","modified_gmt":"2019-05-30T05:35:03","slug":"alpines-museum-zeigt-gletscher-im-treibhaus","status":"publish","type":"post","link":"https:\/\/www.greenpeace.ch\/de\/medienmitteilung\/6682\/alpines-museum-zeigt-gletscher-im-treibhaus\/","title":{"rendered":"Alpines Museum zeigt: Gletscher im Treibhaus"},"content":{"rendered":"<p><b>\u201eGletscher im Treibhaus\u201c \u2013 so lautet der Titel der Ausstellung, die am 1. September im alpinen Museum Bern startet und bis zum 25. M\u00e4rz n\u00e4chsten Jahres zu sehen sein wird. Die Schau dokumentiert mit grossformatigen Bildern das sichtbarste Signal der weltweiten Klimaver\u00e4nderung: den dramatischen R\u00fcckzug der Alpengletscher. Im Zentrum stehen dabei historische Aufnahmen, denen heutige Fotografien der gleichen Motive gegen\u00fcber gestellt werden. Die Tr\u00e4gerschaft der Ausstellung bilden das Alpine Museum zusammen mit dem Schweizer Alpen-Club (SAC) und Greenpeace.<\/b><\/p>\n<div>\n<p class=\"bodytext\">Bern. Der Klimawandel hat die als Alpenland<br \/>\nbesonders davon betroffene Schweiz l\u00e4ngst erreicht. Davon zeugen<br \/>\nnebst den schmelzenden Gletschern als augenf\u00e4lligstem Zeichen auch<br \/>\nextreme Hitzeperioden wie diesen Juli oder im Sommer 03, begleitet<br \/>\nvon einer mit dem Auftauen des Permafrostes zusammenh\u00e4ngenden<br \/>\nZunahme von Felsst\u00fcrzen. Aber auch \u00dcberschwemmungen wie im Sommer<br \/>\n05 und die darauf folgende Trockenperiode geh\u00f6ren zu den<br \/>\nSymptomen.<\/p>\n<p class=\"bodytext\">Greenpeace freut sich, dass &#8220;Gletscher im<br \/>\nTreibhaus&#8221; in einem bedeutenden Schweizer Museum in der N\u00e4he vom<br \/>\nBundeshaus gezeigt werden kann: dem Mittelpunkt des nationalen<br \/>\npolitischen Geschehens, wo nun mit h\u00f6chster Dringlichkeit<br \/>\nEntscheide zu f\u00e4llen und umzusetzen sind, um den Klimawandel<br \/>\naufzuhalten. Allem voran ist eine substantielle Lenkungsabgabe auf<br \/>\nCO2 einzuf\u00fchren. Weitere Instrumente wie zum Beispiel eine Abgabe<br \/>\nauf alle Energien oder verkehrsmindernde Massnahmen sind besser<br \/>\nheute als morgen zu starten. Denn wie der am 24. August von der<br \/>\nKlima-Allianz ver\u00f6ffentlichte Klimamasterplan zeigt: Die<br \/>\nZielvorgabe f\u00fcr die Schweiz heisst, bis 2050 die<br \/>\nTreibhausgas-Emissionen um 90% zu senken, soll das Klima nicht<br \/>\nv\u00f6llig aus den Fugen geraten.<\/p>\n<p class=\"bodytext\">Die von Greenpeace massgeblich mitfinanzierte<br \/>\nWander-Ausstellung war schon in verschiedenen deutschsprachigen<br \/>\nSt\u00e4dten pr\u00e4sent. Sie ist f\u00fcr die Umweltorganisation eine wichtige<br \/>\nGelegenheit, die Problematik der globalen Klimaver\u00e4nderung einem<br \/>\nbreiten Schweizer Publikum auf anschauliche Weise n\u00e4her zu<br \/>\nbringen.<\/p>\n<p class=\"bodytext\"><strong>Kontakt:<\/strong><\/p>\n<p>Alexander Hauri, Klimakampagne Greenpeace 076 399 60<br \/>\n61Greenpeace Medienabteilung 044 447 41 11<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201eGletscher im Treibhaus\u201c \u2013 so lautet der Titel der Ausstellung, die am 1. September im alpinen Museum Bern startet und bis zum 25. M\u00e4rz n\u00e4chsten Jahres zu sehen sein wird.&hellip;<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_planet4_optimize_post_is_variant":false,"_planet4_optimize_experiment_name":"","_planet4_optimize_variant_name":"","ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[1],"tags":[50],"p4-page-type":[71],"gpch-article-type":[],"class_list":["post-6682","post","type-post","status-publish","format-standard","hentry","category-unkategorisiert","tag-klima","p4-page-type-medienmitteilung"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts\/6682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/comments?post=6682"}],"version-history":[{"count":0,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts\/6682\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/media?parent=6682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/categories?post=6682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/tags?post=6682"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/p4-page-type?post=6682"},{"taxonomy":"gpch-article-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/gpch-article-type?post=6682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}