{"id":6726,"date":"2005-10-23T00:00:00","date_gmt":"2005-10-22T22:00:00","guid":{"rendered":"https:\/\/master.greenpeace.ch\/beitrag\/6726\/bienen-halten-sich-nicht-an-gentech-regelungen\/"},"modified":"2019-05-30T07:36:19","modified_gmt":"2019-05-30T05:36:19","slug":"bienen-halten-sich-nicht-an-gentech-regelungen","status":"publish","type":"post","link":"https:\/\/www.greenpeace.ch\/de\/medienmitteilung\/6726\/bienen-halten-sich-nicht-an-gentech-regelungen\/","title":{"rendered":"Bienen halten sich nicht an Gentech-Regelungen"},"content":{"rendered":"<p><b>Bienen kennen keine Grenzen. Sie haben einen Sammel-Radius von mehreren Kilometern und transportieren auch Pollen von Gentech-Pflanzen \u00fcber weite Distanzen. Imkerinnen und Imker sowie Greenpeace haben heute beim Pier 7 am Z\u00fcrcher Utoquai mit einem Massenstart von Bienen-Ballonen verdeutlicht, dass Schweizer Honig mit Gentech-Bestandteilen versetzt sein wird, sollte es in der Schweiz zum Anbau von Gentech-Pflanzen kommen. Momentan l\u00e4uft die Vernehmlassung zur so genannten Koexistenz-Verordnung. Diese suggeriert, dass ein Nebeneinander von Gentech- und gentechfreiem Anbau m\u00f6glich sei. Ein JA zur Gentechfrei-Initiative am 27. November kann aber im Gegensatz erfolgreich verhindern, dass aus Schweizer Qualit\u00e4tsprodukten schon bald Gentech-Produkte werden.<\/b><\/p>\n<div>\n<p class=\"bodytext\">Z\u00fcrich. Mit dem Flug von tausenden<br \/>\nBienen-Ballonen weisen ImkerInnen und Greenpeace Schweiz heute<br \/>\ndarauf hin, dass Bienen sich nicht an festgelegte Distanzen halten.<br \/>\nDie Qualit\u00e4tsmarke \u00abSchweizer Honig\u00bb ist durch den Anbau<br \/>\ngenmanipulierter Pflanzen bedroht. Mit ihrem riesigen Aktionsfeld<br \/>\nsammeln Bienen auch Gentech-Pollen, denn sie unterscheiden nicht<br \/>\nzwischen Gentech- oder gentechfreien Pflanzen. Wie auch<br \/>\nkonventionelles Saatgut oder Lebensmittel wird Honig fr\u00fcher oder<br \/>\nsp\u00e4ter verunreinigt sein, sollten sich einzelne Schweizer Bauern<br \/>\nzur Produktion von Gentech-Pflanzen entschliessen.<\/p>\n<p class=\"bodytext\">In Kanada, wo grossfl\u00e4chig Gentech-Raps<br \/>\nangebaut wird, ist die Produktion von Bio-Raps zum Erliegen<br \/>\ngekommen. Weil es kein gentechfreies Saatgut mehr gibt und<br \/>\nKontaminationen unvermeidbar sind, mussten sogar ganze<br \/>\nBauernbetriebe ihre T\u00e4tigkeit einstellen. Auf dem Reissbrett<br \/>\nerstellte Sicherheitsabst\u00e4nde zwischen Gentech-Acker und<br \/>\nkonventionell bepflanztem Feld greifen in der Praxis offensichtlich<br \/>\nnicht. So wurde in kanadischem Honig bereits mehrfach<br \/>\nGentech-Pollen entdeckt. In Deutschland reichte k\u00fcrzlich ein<br \/>\neinziges Gentech-Feld in der N\u00e4he eines Bienenvolkes aus, um die<br \/>\nganze Ernte eines Imkers zu verunreinigen. Solche Beispiele machen<br \/>\nverst\u00e4ndlich, warum sich nebst einer grossen Mehrheit von<br \/>\nKonsumentInnen und Bauern auch ImkerInnen vor dem Gentech-Anbau in<br \/>\nder Schweiz f\u00fcrchten. William Schneeberger, Pr\u00e4sident des Verbandes<br \/>\nSchweizerischer Bienenz\u00fcchtervereine VSBV meint dazu: \u00abEs braucht<br \/>\nein Moratorium, weil es unm\u00f6glich sein wird, in Gentech-Regionen<br \/>\ngentechfreien Honig zu produzieren. Auch ist unklar, ob<br \/>\nGentech-Kulturen negative Auswirkungen auf Bienenv\u00f6lker haben.<br \/>\nBienen und andere Best\u00e4uber sind aber f\u00fcr die Landwirtschaft<br \/>\nunentbehrlich.\u00bb<\/p>\n<p class=\"bodytext\">Wird die Gentechfrei-Initiative vom Volk am 27.<br \/>\nNovember abgelehnt, steht dem Anbau von Gentech-Pflanzen in der<br \/>\nSchweiz nichts mehr im Wege. Als Grundlage zum Anbau soll die so<br \/>\ngenannte \u00abKoexistenz-Verordnung\u00bb dienen, die sich in der<br \/>\nVernehmlassung befindet. Diese Verordnung wird aber gerade in der<br \/>\nkleinr\u00e4umigen Schweiz in der Praxis kl\u00e4glich versagen.<br \/>\n\u00abGentech-Felder in der Schweiz f\u00fchren zwangsl\u00e4ufig zum Aus f\u00fcr<br \/>\nnat\u00fcrlich produzierte Lebensmittel\u00bb, sagt Marianne K\u00fcnzle von<br \/>\nGreenpeace Schweiz. \u00abEinzig der Verzicht auf Gentechnik in der<br \/>\nLandwirtschaft gew\u00e4hrleistet weiterhin eine Versorgung mit<br \/>\ngentechfreien nat\u00fcrlichen Lebensmitteln. Ein f\u00fcnfj\u00e4hriges<br \/>\nMoratorium ist ein wichtiger Schritt in diese Richtung.\u00bb<\/p>\n<p class=\"bodytext\"><strong>Kontakt:<\/strong><\/p>\n<p>Marianne K\u00fcnzle, Genschutz-Kampagne Greenpeace Schweiz 079 410<br \/>\n76 48<\/p>\n<p>William Schneeberger, Pr\u00e4sident VSBV 032 941 17 72<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bienen kennen keine Grenzen. Sie haben einen Sammel-Radius von mehreren Kilometern und transportieren auch Pollen von Gentech-Pflanzen \u00fcber weite Distanzen. Imkerinnen und Imker sowie Greenpeace haben heute beim Pier 7&hellip;<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_planet4_optimize_post_is_variant":false,"_planet4_optimize_experiment_name":"","_planet4_optimize_variant_name":"","ep_exclude_from_search":false,"gpch_hide_header_image":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[1],"tags":[],"p4-page-type":[71],"gpch-article-type":[],"class_list":["post-6726","post","type-post","status-publish","format-standard","hentry","category-unkategorisiert","p4-page-type-medienmitteilung"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts\/6726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/comments?post=6726"}],"version-history":[{"count":0,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts\/6726\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/media?parent=6726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/categories?post=6726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/tags?post=6726"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/p4-page-type?post=6726"},{"taxonomy":"gpch-article-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/gpch-article-type?post=6726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}