{"id":6972,"date":"2002-10-24T00:00:00","date_gmt":"2002-10-23T22:00:00","guid":{"rendered":"https:\/\/master.greenpeace.ch\/beitrag\/6972\/greenpeace-tankpause-an-saemtlichen-esso-zapfsaeulen-in-luxemburg\/"},"modified":"2019-05-30T07:42:57","modified_gmt":"2019-05-30T05:42:57","slug":"greenpeace-tankpause-an-saemtlichen-esso-zapfsaeulen-in-luxemburg","status":"publish","type":"post","link":"https:\/\/www.greenpeace.ch\/de\/medienmitteilung\/6972\/greenpeace-tankpause-an-saemtlichen-esso-zapfsaeulen-in-luxemburg\/","title":{"rendered":"Greenpeace: Tankpause an s\u00e4mtlichen Esso-Zapfs\u00e4ulen in Luxemburg"},"content":{"rendered":"<p><b>650 Umweltsch\u00fctzer aus aller Welt protestieren gegen die Blockadehaltung des \u00d6lkonzerns beim Klimaschutz. Aus Protest gegen die klimasch\u00e4dliche Politik des \u00d6lkonzerns Esso ketteten sich Greenpeace-Aktivisten aus aller Welt heute fr\u00fch an die Zapfs\u00e4ulen aller 28 Tankstellen des \u00d6lmultis in Luxemburg. Die insgesamt 650 Aktivisten aus 31 L\u00e4ndern, unter anderem aus Deutschland, Frankreich, Spanien, Libanon, Israel, der Schweiz, den USA und Japan spannten an den Tankstellen, darunter auch die gr\u00f6\u00dfte Esso-Tankstelle der Welt, Banner mit der Aufschrift \u201eEsso &#8211; No. 1 Climate Criminal\u201c (Esso \u2013 Klimaverbrecher Nr. 1) und \u201eStop Esso\u201c. Die friedliche Demonstration in Luxemburg, an der auch der internationale Greenpeace-Gesch\u00e4ftsf\u00fchrer Gerd Leipold teilnimmt, ist Teil der weltweiten \u201eStoppt Esso-Woche\u201c von Greenpeace. Sie findet gleichzeitig zur UNO-Klimakonferenz in Neu Delhi\/Indien statt.<\/b><\/p>\n<div>\n<p class=\"bodytext\">Luxemburg\/Z\u00fcrich. Auf der Klimakonferenz<br \/>\ntreffen sich Vertreter von 178 Staaten um \u00fcber die Umsetzung des<br \/>\nKlimaschutzabkommens von Kyoto zu beraten. Die USA sind weltweit<br \/>\nf\u00fcr 25 Prozent der Treibhausgas-Emissionen verantwortlich, nehmen<br \/>\nan der Konferenz jedoch nicht Teil. Die Lobbyarbeit des \u00d6lkonzerns<br \/>\ntr\u00e4gt ma\u00dfgeblich dazu bei, dass sich US-Pr\u00e4sident George Bush bis<br \/>\nheute weigert, das Kyoto-Protokoll zu ratifizieren.<\/p>\n<p>&#8220;Esso unternimmt alles, um die US-Regierung auf ihrem<br \/>\nklimafeindlichen Kurs zu halten&#8221;, sagt Gabriela von Goerne,<br \/>\nKlimaexpertin von Greenpeace, vor Ort in Luxemburg. &#8220;Esso macht<br \/>\nsich mitschuldig an den Folgen zunehmender St\u00fcrme, sintflutartiger<br \/>\nRegenf\u00e4lle und Flutkatastrophen. Der \u00d6lkonzern bestreitet bis<br \/>\nheute, dass die Verbrennung von \u00d6l, Kohle und Gas das Klima erw\u00e4rmt<br \/>\nund die Intensit\u00e4t und H\u00e4ufigkeit von Unwettern erh\u00f6ht.&#8221; Greenpeace<br \/>\nfordert Esso auf, seine Blockadehaltung aufzugeben und endlich in<br \/>\nden Ausbau erneuerbarer Energien zu investieren.<\/p>\n<p>Esso investiert nicht wie andere \u00d6lkonzerne in erneuerbare<br \/>\nEnergien, sondern konzentriert sich ausschlie\u00dflich auf das<br \/>\n\u00d6lgesch\u00e4ft. &#8220;Globale Konzerne wie Esso m\u00fcssen endlich auch globale<br \/>\nVerantwortung zeigen&#8221;, fordert von Goerne. &#8220;Statt mit seinen<br \/>\nMilliarden neue \u00d6lfelder auszubeuten, muss Esso endlich in moderne<br \/>\nEnergieformen investieren, die das Klima nicht weiter<br \/>\naufheizen.&#8221;<\/p>\n<p>Insgesamt investieren der \u00d6l-Konzern Esso bzw. seine<br \/>\nMuttergesellschaft ExxonMobil weltweit j\u00e4hrlich knapp zehn<br \/>\nMilliarden US-Dollar in die Suche und Ausbeutung neuer Erd\u00f6l- und<br \/>\nErdgasvorkommen. Esso verbuchte allein im Jahr 2001 einen Umsatz<br \/>\nvon ca. 213 Milliarden US Dollar. Das entspricht in etwa dem<br \/>\nBruttosozialprodukt von Schweden.<\/p>\n<p><strong>Kontakt:<\/strong><\/p>\n<p>R\u00fcckfragen bitte an den Pressesprecher Cl\u00e9ment Tolusso (vor<br \/>\nOrt), 079 213 41 06 oder an die Klima-Expertin Dr. Gabriela von<br \/>\nGoerne, Tel. 0049 171-8781-191 (ebenfalls vor Ort). Gerd Leipold,<br \/>\nChef von Greenpeace International, erreichen Sie \u00fcber<br \/>\nPressesprecher Bj\u00f6rn Jettka, Tel. 0049 171-8780-778. Fotomaterial<br \/>\nvon der Aktion erhalten Sie unter Tel. 0049 40-30618-377,<br \/>\nBetaSP-Material unter Tel. 0049 40-42910110.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>650 Umweltsch\u00fctzer aus aller Welt protestieren gegen die Blockadehaltung des \u00d6lkonzerns beim Klimaschutz. Aus Protest gegen die klimasch\u00e4dliche Politik des \u00d6lkonzerns Esso ketteten sich Greenpeace-Aktivisten aus aller Welt heute fr\u00fch&hellip;<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_planet4_optimize_post_is_variant":false,"_planet4_optimize_experiment_name":"","_planet4_optimize_variant_name":"","ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[1],"tags":[50],"p4-page-type":[71],"gpch-article-type":[],"class_list":["post-6972","post","type-post","status-publish","format-standard","hentry","category-unkategorisiert","tag-klima","p4-page-type-medienmitteilung"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts\/6972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/comments?post=6972"}],"version-history":[{"count":0,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/posts\/6972\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/media?parent=6972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/categories?post=6972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/tags?post=6972"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/p4-page-type?post=6972"},{"taxonomy":"gpch-article-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/de\/wp-json\/wp\/v2\/gpch-article-type?post=6972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}