{"id":105134,"date":"2023-12-07T15:03:00","date_gmt":"2023-12-07T14:03:00","guid":{"rendered":"https:\/\/www.greenpeace.ch\/?p=105134"},"modified":"2023-12-20T22:10:25","modified_gmt":"2023-12-20T21:10:25","slug":"72000-signatures-contre-les-extensions-autoroutieres","status":"publish","type":"post","link":"https:\/\/www.greenpeace.ch\/fr\/communique-de-presse\/105134\/72000-signatures-contre-les-extensions-autoroutieres\/","title":{"rendered":"72&#8217;000 signatures contre les extensions autorouti\u00e8res"},"content":{"rendered":"\n<p><strong>Moins que deux mois apr\u00e8s le lancement du r\u00e9f\u00e9rendum, l\u2019alliance pour le r\u00e9f\u00e9rendum a d\u00e9j\u00e0 r\u00e9colt\u00e9 72&#8217;000 signatures contre l\u2019extension d\u00e9mesur\u00e9e du r\u00e9seau autoroutier d\u00e9cid\u00e9e par le Conseil f\u00e9d\u00e9ral et le Parlement. Il est ainsi d\u00e9j\u00e0 certain que le peuple pourra se prononcer sur ces extensions chiffr\u00e9es \u00e0 5,3 milliards de francs.<\/strong><\/p>\n\n<p>La campagne de r\u00e9colte des signatures a d\u00e9montr\u00e9 clairement que ce r\u00e9f\u00e9rendum suscite un grand int\u00e9r\u00eat: \u00abNous avons \u00e0 l\u2019\u00e9vidence touch\u00e9 une corde sensible. Nombreuses sont les personnes qui trouvent insens\u00e9 que la Conf\u00e9d\u00e9ration, en pleine crise climatique, d\u00e9cide de d\u00e9penser des milliards dans la construction autorouti\u00e8re et de d\u00e9truire ainsi de pr\u00e9cieuses terres agricoles\u00bb, constate Martin Winder, Responsable de l\u2019ATE Association transports et environnement pour la campagne du r\u00e9f\u00e9rendum.&nbsp;<\/p>\n\n<p>\u00abCe soutien perceptible et le rapide succ\u00e8s du r\u00e9f\u00e9rendum nous confortent dans notre \u00e9lan pour stopper cette folie de construction autorouti\u00e8re. Nous sommes pr\u00eats pour la campagne de votation et nous nous en r\u00e9jouissons d\u2019avance!\u00bb Les signatures r\u00e9colt\u00e9es sont en cours d\u2019authentification et seront d\u00e9pos\u00e9es aupr\u00e8s de la Chancellerie f\u00e9d\u00e9rale d\u00e9but 2024 \u2013 le d\u00e9lai de remise est fix\u00e9 au 18 janvier 2024. Les votant\u2219e\u2219s pourront donner leur avis sur ces extensions d\u2019autoroute l\u2019ann\u00e9e prochaine encore. \u00abNous sommes convaincus qu\u2019une majorit\u00e9 se prononcera contre ces projets d\u2019extensions autorouti\u00e8res nuisibles au climat\u00bb, pr\u00e9cise pour sa part Silas Hobi, Directeur d\u2019actif-trafiC.\u00a0<\/p>\n\n<h2 class=\"wp-block-heading\">Une large alliance<\/h2>\n\n<p>L\u2019ATE et actif-trafiC ont r\u00e9colt\u00e9 les signatures avec le soutien du PS, des Vert-e-s et d\u2019une vaste coalition de 24 autres associations, partis et organisations environnementales. <\/p>\n\n<p>Le r\u00e9f\u00e9rendum est activement soutenu par: actif-trafiC, Alliance Climatique Suisse, Association des petits paysans, Association suisse pour la protection du climat, ATE Association transports et environnement, BirdLife Suisse, Cittadini per il territorio, Greenpeace Suisse, Initiative des Alpes, jeuneATE, Jeunes Vert-e-s Suisse, Jeunesse socialiste suisse, Komitee zum Schutz des Seer\u00fcckens, L\u00e4bigi Klus, Les VERT-E-S suisses, M\u00e9decins en faveur de l&#8217;Environnement (MfE), Mobilit\u00e9 pi\u00e9tonne Suisse, Non \u00e0 Marly-Matran, Parti socialiste suisse, Parti vert&#8217;lib\u00e9ral Suisse, Pro Natura, Pro Velo Suisse, Schweizerische Energie-Stiftung, Verein Spurwechsel, Vereinigung B\u00fcndner Umweltorganisationen, WeCollect, WWF Suisse.<\/p>\n\n<h2 class=\"wp-block-heading\">Information<\/h2>\n\n<p><a href=\"https:\/\/www.folie-autoroutiere.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.folie-autoroutiere.ch<\/a><\/p>\n\n<h2 class=\"wp-block-heading\">Contact<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Greenpeace Suisse: Nathan Solothurnmann, expert des questions climatiques, 076 514 90 48,\u00a0<a href=\"mailto:nathan.solothurnmann@greenpeace.org\">nathan.solothurnmann@greenpeace.org<\/a><\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li>ATE: Martin Winder, Responsable de la campagne, 031 328 58 63<\/li>\n\n\n\n<li>actif-trafiC: Silas Hobi, Directeur, 079 899 09 18<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Moins que deux mois apr\u00e8s le lancement du r\u00e9f\u00e9rendum, l\u2019alliance pour le r\u00e9f\u00e9rendum a d\u00e9j\u00e0 r\u00e9colt\u00e9 72&#8217;000 signatures contre l\u2019extension d\u00e9mesur\u00e9e du r\u00e9seau autoroutier d\u00e9cid\u00e9e par le Conseil f\u00e9d\u00e9ral et le Parlement.<\/p>\n","protected":false},"author":39,"featured_media":105130,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_planet4_optimize_post_is_variant":false,"_planet4_optimize_experiment_name":"","_planet4_optimize_variant_name":"","ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[22],"tags":[58],"p4-page-type":[73],"gpch-article-type":[],"class_list":["post-105134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-climat","p4-page-type-communique-de-presse"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/105134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/comments?post=105134"}],"version-history":[{"count":0,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/105134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/media\/105130"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/media?parent=105134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/categories?post=105134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/tags?post=105134"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/p4-page-type?post=105134"},{"taxonomy":"gpch-article-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/gpch-article-type?post=105134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}