{"id":116859,"date":"2025-01-29T13:12:19","date_gmt":"2025-01-29T12:12:19","guid":{"rendered":"https:\/\/www.greenpeace.ch\/?p=116859"},"modified":"2025-01-29T13:12:23","modified_gmt":"2025-01-29T12:12:23","slug":"conseil-federal-renonce","status":"publish","type":"post","link":"https:\/\/www.greenpeace.ch\/fr\/communique-de-presse\/116859\/conseil-federal-renonce\/","title":{"rendered":"Climat: le Conseil f\u00e9d\u00e9ral renonce \u00e0 la limite de 1,5\u00b0C, pourtant vitale"},"content":{"rendered":"\n<p><strong>Le Conseil f\u00e9d\u00e9ral a adopt\u00e9 aujourd&#8217;hui <\/strong><a href=\"https:\/\/www.admin.ch\/gov\/fr\/accueil\/documentation\/communiques.msg-id-103949.html\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>un nouvel objectif<\/strong><\/a><strong> de r\u00e9duction des \u00e9missions de CO2 pour la Suisse dans le cadre de l&#8217;Accord de Paris.\u00a0<\/strong><\/p>\n\n<p><em>Georg Klingler, expert des questions climatiques pour Greenpeace Suisse, commente les annonces du Conseil f\u00e9d\u00e9ral:<\/em><\/p>\n\n<p>\u201cLe Conseil f\u00e9d\u00e9ral affirme que les objectifs de r\u00e9duction des \u00e9missions, rendus publics aujourd\u2019hui, sont compatibles avec le respect de la limite d\u2019une \u00e9l\u00e9vation globale des temp\u00e9ratures de 1,5 \u00b0C. C&#8217;est purement et simplement du greenwashing! Le Conseil f\u00e9d\u00e9ral se montre incapable de fournir une d\u00e9monstration scientifique du fait que les ambitions actuelles de la Suisse permettent effectivement de limiter le r\u00e9chauffement climatique global sous la limite de 1,5\u00b0C. Bien au contraire, il pr\u00e9voit de contracter une \u00e9norme dette climatique et adopte un mod\u00e8le qui privil\u00e9gie fortement les pays riches.\u201d<\/p>\n\n<p>\u201cAvec les objectifs climatiques adopt\u00e9s aujourd&#8217;hui pour 2035, le Conseil f\u00e9d\u00e9ral abandonne de fait l\u2019objectif de limiter le r\u00e9chauffement \u00e0 1,5\u00b0C. Cette limite est pourtant essentielle \u00e0 la survie de l&#8217;humanit\u00e9. Ce faisant, il ignore l&#8217;arr\u00eat de la Cour europ\u00e9enne des droits de l&#8217;homme dans l\u2019affaire des A\u00een\u00e9es pour le climat Suisse. Autrement dit, il accepte une \u00e9volution du climat qui va g\u00e9n\u00e9rer de nombreux d\u00e9c\u00e8s pourtant \u00e9vitables. <a href=\"https:\/\/www.nature.com\/articles\/s41591-024-03452-2\" target=\"_blank\" rel=\"noreferrer noopener\">Une \u00e9tude r\u00e9cente<\/a> montre par exemple que des millions de morts risquent de survenir dans toute l&#8217;Europe si le cours actuel du r\u00e9chauffement climatique reste inchang\u00e9.\u201d\u00a0<\/p>\n\n<p>\u201cPour respecter la limite des 1,5\u00b0C, la Suisse doit se fixer <a href=\"https:\/\/www.greenpeace.ch\/fr\/communique-de-presse\/116808\/mise-en-oeuvre-ainees\/\" target=\"_blank\" rel=\"noreferrer noopener\">un objectif de baisse des \u00e9missions<\/a> carbones qui correspond avec le budget carbone restant dans le monde. Cela implique de doubler les efforts de r\u00e9duction en Suisse et \u00e0 l&#8217;\u00e9tranger. <a href=\"https:\/\/www.greenpeace.ch\/fr\/communique-de-presse\/114601\/climat-grosse-gamelle-de-la-suisse-dans-le-classement-climatique-par-pays\/\" target=\"_blank\" rel=\"noreferrer noopener\">Certains pays se montrent beaucoup plus ambitieux dans ce domaine<\/a>. Le Danemark, par exemple, pr\u00e9voit de r\u00e9duire ses propres \u00e9missions de 70% d&#8217;ici \u00e0 2030.\u201d<\/p>\n\n<p>\u201cAvec la politique climatique pr\u00e9sent\u00e9e aujourd&#8217;hui, la Suisse souhaite avantager lourdement les pays riches, comme l&#8217;illustre en un coup d&#8217;\u0153il la comparaison entre la Suisse et l&#8217;Inde.\u201d&nbsp;<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXfJdSsKJRRpcMnd4pmy_exZa-do0cUYDrjhIsthdSiR-OlQq-fpFIWoqvOS0BcNOImPakKtwesSExx_gOe75G9radeFCQz6NlItgFyWnnDLxhD8EIYzzH0b5FkspDaCRmMPjwJJyg?key=Jrbphxl5RHJH9vOtt2ODGtsk\" alt=\"\"\/><\/figure>\n\n<p><em>Le mod\u00e8le lin\u00e9aire pr\u00e9vu par la Suisse pour la r\u00e9duction des \u00e9missions aboutit \u00e0 une situation largement \u00e0 l\u2019avantage des pays les plus riches. (Infographies disponibles sur demande pour les m\u00e9dias)&nbsp;<\/em><\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Contact<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Georg Klingler, expert climat et \u00e9nergie, Greenpeace Suisse, +41 79 785 07 38, <a href=\"mailto:georg.klingler@greenpeace.org\">georg.klingler@greenpeace.org<\/a><\/li>\n\n\n\n<li>Mathias Schlegel, porte-parole, Greenpeace Suisse, +41 79 794 61 23, <a href=\"mailto:mathias.schlegel@greenpeace.org\">mathias.schlegel@greenpeace.org<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le Conseil f\u00e9d\u00e9ral a adopt\u00e9 aujourd\u2019hui un nouvel objectif de r\u00e9duction des \u00e9missions de CO2 pour la Suisse dans le cadre de l\u2019Accord de Paris.\u00a0Le Conseil f\u00e9d\u00e9ral affirme que les objectifs de r\u00e9duction des \u00e9missions, rendus publics aujourd\u2019hui, sont compatibles avec le respect de la limite d\u2019une \u00e9l\u00e9vation globale des temp\u00e9ratures de 1,5 \u00b0C. C&#8217;est purement et simplement du greenwashing!<\/p>\n","protected":false},"author":37,"featured_media":116445,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_planet4_optimize_post_is_variant":false,"_planet4_optimize_experiment_name":"","_planet4_optimize_variant_name":"","ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[22],"tags":[58,136,204],"p4-page-type":[73],"gpch-article-type":[],"class_list":["post-116859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-climat","tag-justice-climatique","tag-loi-co2","p4-page-type-communique-de-presse"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/116859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/comments?post=116859"}],"version-history":[{"count":1,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/116859\/revisions"}],"predecessor-version":[{"id":116860,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/116859\/revisions\/116860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/media\/116445"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/media?parent=116859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/categories?post=116859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/tags?post=116859"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/p4-page-type?post=116859"},{"taxonomy":"gpch-article-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/gpch-article-type?post=116859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}