{"id":128081,"date":"2025-12-17T00:01:00","date_gmt":"2025-12-16T23:01:00","guid":{"rendered":"https:\/\/www.greenpeace.ch\/?p=128081"},"modified":"2025-12-17T08:21:02","modified_gmt":"2025-12-17T07:21:02","slug":"premieres-classes-nocives","status":"publish","type":"post","link":"https:\/\/www.greenpeace.ch\/fr\/communique-de-presse\/128081\/premieres-classes-nocives\/","title":{"rendered":"Aviation: les premi\u00e8res classes sont plus nocives pour le climat"},"content":{"rendered":"\n<p><strong>Une nouvelle \u00e9tude montre que les voyages en premi\u00e8re classe et en classe affaire g\u00e9n\u00e8rent jusqu&#8217;\u00e0 cinq fois plus d&#8217;\u00e9missions nocives pour le climat que les vols en classe \u00e9conomique.&nbsp;<\/strong><\/p>\n\n<p>Les vols en premi\u00e8re classe et en classe affaire nuisent particuli\u00e8rement au climat. Ils sont \u00e0 l\u2019origine de 36 % des \u00e9missions nocives pour le climat de l\u2019aviation commerciale, mais repr\u00e9sentent seulement 14 % des voyageur\u00b7ses. Ce sont les conclusions d\u2019une nouvelle \u00e9tude command\u00e9e par Greenpeace Europe centrale et orientale, \u201c<a href=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2025\/12\/3410dd13-factsheets-businessfirstclass-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Booking of business and first class flights in Europe<\/em><\/a>\u201d(1).<\/p>\n\n<p>Au total, les vols en premi\u00e8re classe et en classe affaire g\u00e9n\u00e8rent jusqu&#8217;\u00e0 cinq fois plus d&#8217;\u00e9missions de CO2 par passager-kilom\u00e8tre que ceux en classe \u00e9conomique. La diff\u00e9rence s\u2019explique par l\u2019espace et le poids plus \u00e9lev\u00e9 occup\u00e9 par les passager\u00b7\u00e8res de ces classes haut de gamme.<\/p>\n\n<p>Si une taxation internationale des billets d&#8217;avion est indispensable pour r\u00e9duire la nocivit\u00e9 de l&#8217;aviation commerciale pour le climat, celle-ci doit \u00eatre plus \u00e9lev\u00e9e pour les vols en premi\u00e8re classe et en classe affaire.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Le boom des vols de luxe&nbsp;<\/strong><\/h3>\n\n<p>Rien que l\u2019ann\u00e9e derni\u00e8re les compagnies a\u00e9riennes ont vendu environ 19 millions de billets haut de gamme (premi\u00e8re classe, classe affaire et premium economy class) pour des vols long-courriers au d\u00e9part de l&#8217;Europe. Un chiffre \u00e9lev\u00e9 qui refl\u00e8te <a href=\"https:\/\/www.iata.org\/en\/pressroom\/2025-releases\/2025-08-04-01\/\" target=\"_blank\" rel=\"noreferrer noopener\">la tendance croissante<\/a> des compagnies a\u00e9riennes europ\u00e9ennes \u00e0 se tourner vers les voyageur\u00b7euses particuli\u00e8rement fortun\u00e9\u00b7es.<\/p>\n\n<p>Les passager\u00b7\u00e8res des vols les plus nocifs doivent assumer cette charge suppl\u00e9mentaire pour le climat. Une taxe minimale de 340 euros sur chaque billet de premi\u00e8re classe vendu en Europe, de 220 euros sur chaque billet en classe affaire pour un vol long-courrier et de 75 euros sur chaque billet en premium economy rapporterait au moins 3,3 milliards d&#8217;euros de recettes fiscales \u00e0 l&#8217;Europe par ann\u00e9e. (2) Des recettes qui pourraient servir \u00e0 rendre<a href=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2025\/12\/20251217-Beilage-zur-MM.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> plus abordables les transports publics ou \u00e0 financer des mesures de protection du climat<\/a>.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Les Suisses favorables \u00e0 la taxation des billets d\u2019avion<\/strong><\/h3>\n\n<p>En Suisse, la question de la taxation des billets d&#8217;avion est aussi d&#8217;actualit\u00e9. <a href=\"https:\/\/www.are.admin.ch\/fr\/couts-benefices\" target=\"_blank\" rel=\"noreferrer noopener\">Selon l&#8217;Office f\u00e9d\u00e9ral du d\u00e9veloppement territorial (ARE)<\/a>, les co\u00fbts externes du trafic a\u00e9rien s&#8217;\u00e9l\u00e8vent \u00e0 pr\u00e8s de 3,9 milliards de francs par an. Et <a href=\"https:\/\/www.parlament.ch\/fr\/ratsbetrieb\/suche-curia-vista\/geschaeft?AffairId=20214259\" target=\"_blank\" rel=\"noreferrer noopener\">selon le Conseil f\u00e9d\u00e9ral<\/a>, le v\u00e9ritable impact du trafic a\u00e9rien est tr\u00e8s \u00e9lev\u00e9, avec une part de 27% des \u00e9missions globales. De fait, dans <a href=\"https:\/\/www.actif-trafic.ch\/tba\" target=\"_blank\" rel=\"noreferrer noopener\">un sondage<\/a> r\u00e9alis\u00e9 en 2022 par gfs-z\u00fcrich pour le compte de l&#8217;organisation environnementale actif-trafiC, 72% des personnes interrog\u00e9es se sont prononc\u00e9es en faveur d&#8217;une taxe sur les billets d&#8217;avion.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Notes: <\/strong><\/h3>\n\n<p><strong><br><\/strong>(1) Les auteur\u00b7es de l&#8217;\u00e9tude du groupe de r\u00e9flexion allemand T3 Transportation Think Tank ont analys\u00e9, pour le compte de Greenpeace Europe centrale et orientale, les vols long-courriers au d\u00e9part de 44 pays europ\u00e9ens, dont la Suisse (depuis Zurich et Gen\u00e8ve). L&#8217;\u00e9tude a pris en compte 24 compagnies a\u00e9riennes europ\u00e9ennes (dont Swiss) et 16 types d&#8217;avions. Les auteur\u00b7es de l&#8217;\u00e9tude ont utilis\u00e9 les donn\u00e9es les plus r\u00e9centes disponibles, datant de 2024.<\/p>\n\n<p>(2) Le montant des taxes sur les billets d&#8217;avion, fix\u00e9 \u00e0 340 euros (premi\u00e8re classe) et 220 euros (classe affaire), est bas\u00e9 sur le guide publi\u00e9 par le groupe de travail <a href=\"https:\/\/solidaritylevies.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Global Solidarity Levies Task Force<\/a>. Le montant de 75 euros pour la premium economy class r\u00e9sulte du fait que les vols dans cette cat\u00e9gorie g\u00e9n\u00e8rent environ un tiers des \u00e9missions des classes affaires.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Plus d\u2019informations:<\/strong>&nbsp;<\/h3>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2025\/12\/20251217-Beilage-zur-MM.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Greenpeace conclusions and recommendations on the T3 analysis \u201cBooking of business and first class flights in Europe&#8221;,<\/em><\/a> Greenpeace Europe centrale et orientale, d\u00e9cembre 2025<\/li>\n\n\n\n<li><a href=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2025\/12\/3410dd13-factsheets-businessfirstclass-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Booking of business and first class flights in Europe<\/em><\/a>, T3 Transportation Think Tank gGmbH sur mandat de Greenpeace Europe centrale et orientale, d\u00e9cembre 2025<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\"><strong>Contacts:<\/strong>&nbsp;<\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Herwig Schuster, expert des questions li\u00e9es au transport, Greenpeace Europe centrale et orientale, +43 664 431 92 14, <a href=\"mailto:herwig.schuster@greenpeace.org\">herwig.schuster@greenpeace.org<\/a>\u00a0<\/li>\n\n\n\n<li>Mathias Schlegel, porte-parole pour Greenpeace Suisse, +41 79 794 61 23, <a href=\"mailto:mathias.schlegel@greenpeace.org\">mathias.schlegel@greenpeace.org<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Une nouvelle \u00e9tude montre que les voyages en premi\u00e8re classe et en classe affaire g\u00e9n\u00e8rent jusqu&#8217;\u00e0 cinq fois plus d&#8217;\u00e9missions nocives pour le climat que les vols en classe \u00e9conomique.\u00a0<\/p>\n","protected":false},"author":37,"featured_media":128083,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_planet4_optimize_post_is_variant":false,"_planet4_optimize_experiment_name":"","_planet4_optimize_variant_name":"","ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[22],"tags":[136,58],"p4-page-type":[73],"gpch-article-type":[],"class_list":["post-128081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-justice-climatique","tag-climat","p4-page-type-communique-de-presse"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/128081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/comments?post=128081"}],"version-history":[{"count":2,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/128081\/revisions"}],"predecessor-version":[{"id":128086,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/128081\/revisions\/128086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/media\/128083"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/media?parent=128081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/categories?post=128081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/tags?post=128081"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/p4-page-type?post=128081"},{"taxonomy":"gpch-article-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/gpch-article-type?post=128081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}