{"id":87522,"date":"2022-07-07T13:01:25","date_gmt":"2022-07-07T11:01:25","guid":{"rendered":"https:\/\/www.greenpeace.ch\/article-de-magazine\/87522\/tiefseegasprojekt-bedroht-wale\/"},"modified":"2022-07-07T16:28:10","modified_gmt":"2022-07-07T14:28:10","slug":"projet-eaux-profondes-baleines","status":"publish","type":"post","link":"https:\/\/www.greenpeace.ch\/fr\/story-fr\/87522\/projet-eaux-profondes-baleines\/","title":{"rendered":"Un projet de gaz en eaux profondes menace les baleines"},"content":{"rendered":"\n<p><strong><strong>Aujourd&#8217;hui, des militant\u00b7e\u00b7s Greenpeace Allemagne ont manifest\u00e9 contre le projet de gaz en eaux profondes de l&#8217;entreprise \u00e9nerg\u00e9tique australienne Woodside. Le fournisseur d&#8217;\u00e9nergie allemand RWE veut cofinancer le projet. En projetant une baleine sur la centrale \u00e9lectrique de RWE \u00e0 Lingen, les activistes demandent \u00e0 RWE de se retirer de ce projet qui aurait des cons\u00e9quences d\u00e9sastreuses pour la nature et les animaux de la r\u00e9gion.<\/strong><\/strong><\/p>\n\n<p>De nombreuses personnes s&#8217;inqui\u00e8tent de l&#8217;approvisionnement en \u00e9nergie. Dans les d\u00e9bats, cela se fait parfois au d\u00e9triment du climat et de la biodiversit\u00e9 &#8211; les entreprises veulent profiter de cette situation pour faire du chiffre. Mais la crise climatique et la crise de la biodiversit\u00e9 n&#8217;ont pas disparu. C&#8217;est pourquoi nous devons nous concentrer sur une utilisation plus \u00e9conome des ressources existantes et ne pas lancer de nouveaux projets fossiles. Le groupe australien Woodsidene se soucie pas de ces consid\u00e9rations. Ses projets de forage de gaz naturel dans la mer au large de l&#8217;Australie occidentale auront de graves cons\u00e9quences pour la vie sous-marine au large des c\u00f4tes. Les baleines sont particuli\u00e8rement menac\u00e9es par ce projet. Dans une \u00e9tude publi\u00e9e aujourd&#8217;hui et intitul\u00e9e &#8220;<a href=\"https:\/\/www.greenpeace.de\/publikationen\/Moby%20Sick_Whales%20Report_GAP_2.pdf\">Moby Sick : The Costs of Woodside&#8217;s Burrup Hub for Threatened Whales<\/a>&#8220;, Greenpeace Autralie et Pacifique a identifi\u00e9 cinq risques principaux auxquels les animaux sont expos\u00e9s suite \u00e0 l&#8217;extraction de gaz offshore. Les baleines sont tr\u00e8s sensibles au bruit subaquatique, car elles utilisent le son et le sonar de fa\u00e7on tr\u00e8s efficace pour communiquer, naviguer et se nourrir. Outre le bruit des op\u00e9rations de forage et de dragage, l&#8217;\u00e9tude indique qu&#8217;elles sont \u00e9galement affect\u00e9es par les \u00e9tudes sismiques, les effets \u00e9cotoxicologiques, les collisions avec les navires et la crise climatique.<\/p>\n<div data-render=\"planet4-blocks\/gallery\" data-attributes=\"{&quot;attributes&quot;:{&quot;multiple_image&quot;:&quot;87538,87541,87544&quot;,&quot;image_data&quot;:[{&quot;url&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/00e7b827-gp1sxrsu_medium_res.jpg&quot;,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5},&quot;id&quot;:87538},{&quot;url&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/4aad3a76-gp1sxrsx_medium_res.jpg&quot;,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5},&quot;id&quot;:87541},{&quot;url&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/bc45fd11-gp1sxru2_medium_res.jpg&quot;,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5},&quot;id&quot;:87544}],&quot;gallery_block_style&quot;:0,&quot;gallery_block_title&quot;:&quot;&quot;,&quot;gallery_block_description&quot;:&quot;&quot;,&quot;gallery_block_focus_points&quot;:&quot;&quot;,&quot;images&quot;:[{&quot;image_src&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/00e7b827-gp1sxrsu_medium_res.jpg&quot;,&quot;image_srcset&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/00e7b827-gp1sxrsu_medium_res.jpg 1200w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/00e7b827-gp1sxrsu_medium_res-300x200.jpg 300w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/00e7b827-gp1sxrsu_medium_res-1024x683.jpg 1024w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/00e7b827-gp1sxrsu_medium_res-768x512.jpg 768w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/00e7b827-gp1sxrsu_medium_res-510x340.jpg 510w&quot;,&quot;image_sizes&quot;:false,&quot;alt_text&quot;:&quot;&quot;,&quot;caption&quot;:&quot;RWE participe \\u00e0 un projet de gaz naturel liqu\\u00e9fi\\u00e9 de la soci\\u00e9t\\u00e9 australienne Woodside. Il s&#039;agit du plus grand projet de gaz naturel jamais r\\u00e9alis\\u00e9 dans le pays, au large de la c\\u00f4te ouest-australienne. Le forage et le dynamitage des fonds marins n\\u00e9cessaires menacent l&#039;habitat et les voies de migration des baleines qui y vivent.  \\u00a9 Marcus Meyer \\\/ Greenpeace&quot;,&quot;focus_image&quot;:&quot;&quot;,&quot;credits&quot;:&quot;&quot;},{&quot;image_src&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/4aad3a76-gp1sxrsx_medium_res.jpg&quot;,&quot;image_srcset&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/4aad3a76-gp1sxrsx_medium_res.jpg 1200w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/4aad3a76-gp1sxrsx_medium_res-300x200.jpg 300w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/4aad3a76-gp1sxrsx_medium_res-1024x683.jpg 1024w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/4aad3a76-gp1sxrsx_medium_res-768x512.jpg 768w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/4aad3a76-gp1sxrsx_medium_res-510x340.jpg 510w&quot;,&quot;image_sizes&quot;:false,&quot;alt_text&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Sur la tour de refroidissement de la centrale \\u00e9lectrique RWE, ils projettent l&#039;image d&#039;une baleine avec son baleineau nouveau-n\\u00e9 et la revendication \\&quot;RWE, CHOOSE WHALES, NOT WOODSIDE\\&quot;.  \\u00a9 Marcus Meyer \\\/ Greenpeace&quot;,&quot;focus_image&quot;:&quot;&quot;,&quot;credits&quot;:&quot;&quot;},{&quot;image_src&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/bc45fd11-gp1sxru2_medium_res.jpg&quot;,&quot;image_srcset&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/bc45fd11-gp1sxru2_medium_res.jpg 800w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/bc45fd11-gp1sxru2_medium_res-200x300.jpg 200w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/bc45fd11-gp1sxru2_medium_res-683x1024.jpg 683w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/bc45fd11-gp1sxru2_medium_res-768x1152.jpg 768w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/bc45fd11-gp1sxru2_medium_res-227x340.jpg 227w&quot;,&quot;image_sizes&quot;:false,&quot;alt_text&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Des militant\\u00b7e\\u00b7s Greenpeace manifestent contre la participation du groupe \\u00e9nerg\\u00e9tique RWE d&#039;Essen \\u00e0 un projet de gaz naturel \\u00e9cologiquement nocif en Australie, \\u00e0 la centrale \\u00e0 gaz de Lingen.  \\u00a9 Marcus Meyer \\\/ Greenpeace&quot;,&quot;focus_image&quot;:&quot;&quot;,&quot;credits&quot;:&quot;&quot;}]}}\"><\/div>\n<h2 class=\"wp-block-heading\"><strong><strong>Quel est l&#8217;enjeu du projet gazier Woodside au large de l&#8217;Australie ?\u00a0<\/strong><\/strong><\/h2>\n\n<p>Le plus grand groupe p\u00e9trolier et gazier australien Woodside veut, dans une premi\u00e8re phase, exploiter un champ de gaz naturel en mer \u00e0 300 kilom\u00e8tres au large de la c\u00f4te d&#8217;Australie occidentale. Cela signifie de 8 \u00e0 84 puits de gaz \u00e0 plus de 900 m\u00e8tres de profondeur et une plate-forme offshore flottante. Le projet Scarborough, qui sera suivi dans une deuxi\u00e8me phase par Browse avec deux autres plates-formes de forage, est irresponsable \u00e0 plus d&#8217;un titre : l&#8217;extraction de gaz naturel \u00e0 cet endroit d\u00e9truit l&#8217;habitat et les voies de migration des baleines et de nombreuses autres esp\u00e8ces &#8211; et il est extr\u00eamement nuisible pour le climat.<\/p>\n\n<p>Le d\u00e9veloppement de Scarborough n\u00e9cessiterait le dynamitage et le dragage de plus de centaines de kilom\u00e8tres de fonds marins, l&#8217;enfoncement d&#8217;\u00e9normes pieux en b\u00e9ton dans les fonds marins et le d\u00e9versement de millions de tonnes de coraux et de roches broy\u00e9s dans l&#8217;archipel de Dampier,qui abrite la plus grande biodiversit\u00e9 marine au large de l&#8217;Australie occidentale. La zone abrite des milliers d&#8217;esp\u00e8ces de baleines, de requins, de poissons, de tortues et de coraux. Elle se trouve sur les voies de migration des baleines et abrite de nombreuses esp\u00e8ces menac\u00e9es. De plus, le transport de la mati\u00e8re premi\u00e8re n\u00e9cessite la pose de centaines de kilom\u00e8tres de pipeline sous l&#8217;eau ; le pipeline de Scarborough traverserait le parc marin de Montebello, l&#8217;un des plus importants sites de reproduction et de nidification des tortues marines.<\/p>\n<div data-render=\"planet4-blocks\/gallery\" data-attributes=\"{&quot;attributes&quot;:{&quot;multiple_image&quot;:&quot;87528,87531,87534&quot;,&quot;image_data&quot;:[{&quot;url&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/58ca1b67-gp1sxooz_medium_res.jpg&quot;,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5},&quot;id&quot;:87528},{&quot;url&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/871c21ca-gp1sxopg_medium_res.jpg&quot;,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5},&quot;id&quot;:87531},{&quot;url&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/d7d90e17-gp1sxpst_medium_res.jpg&quot;,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5},&quot;id&quot;:87534}],&quot;gallery_block_style&quot;:0,&quot;gallery_block_title&quot;:&quot;&quot;,&quot;gallery_block_description&quot;:&quot;&quot;,&quot;gallery_block_focus_points&quot;:&quot;&quot;,&quot;images&quot;:[{&quot;image_src&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/58ca1b67-gp1sxooz_medium_res.jpg&quot;,&quot;image_srcset&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/58ca1b67-gp1sxooz_medium_res.jpg 1200w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/58ca1b67-gp1sxooz_medium_res-300x213.jpg 300w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/58ca1b67-gp1sxooz_medium_res-1024x728.jpg 1024w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/58ca1b67-gp1sxooz_medium_res-768x546.jpg 768w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/58ca1b67-gp1sxooz_medium_res-478x340.jpg 478w&quot;,&quot;image_sizes&quot;:false,&quot;alt_text&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Baleine \\u00e0 bosse nouveau-n\\u00e9e lors de ses premi\\u00e8res respirations. \\u00a9 Alex Westover \\\/ Greenpeace&quot;,&quot;focus_image&quot;:&quot;&quot;,&quot;credits&quot;:&quot;&quot;},{&quot;image_src&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/871c21ca-gp1sxopg_medium_res.jpg&quot;,&quot;image_srcset&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/871c21ca-gp1sxopg_medium_res.jpg 1200w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/871c21ca-gp1sxopg_medium_res-300x212.jpg 300w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/871c21ca-gp1sxopg_medium_res-1024x724.jpg 1024w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/871c21ca-gp1sxopg_medium_res-768x543.jpg 768w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/871c21ca-gp1sxopg_medium_res-481x340.jpg 481w&quot;,&quot;image_sizes&quot;:false,&quot;alt_text&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Les baleines \\u00e0 bosse migrent vers le nord, dans les eaux chaudes du golfe de Ningaloo, pour donner naissance \\u00e0 leurs baleineaux.  \\u00a9 Alex Westover \\\/ Greenpeace&quot;,&quot;focus_image&quot;:&quot;&quot;,&quot;credits&quot;:&quot;&quot;},{&quot;image_src&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/d7d90e17-gp1sxpst_medium_res.jpg&quot;,&quot;image_srcset&quot;:&quot;https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/d7d90e17-gp1sxpst_medium_res.jpg 1200w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/d7d90e17-gp1sxpst_medium_res-300x200.jpg 300w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/d7d90e17-gp1sxpst_medium_res-1024x683.jpg 1024w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/d7d90e17-gp1sxpst_medium_res-768x512.jpg 768w, https:\\\/\\\/www.greenpeace.ch\\\/static\\\/planet4-switzerland-stateless\\\/2022\\\/07\\\/d7d90e17-gp1sxpst_medium_res-510x340.jpg 510w&quot;,&quot;image_sizes&quot;:false,&quot;alt_text&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Nous avons photographi\\u00e9 cette baleine \\u00e0 bosse qui venait de na\\u00eetreau large du r\\u00e9cif de Ningaloo. Ces photos montrent le baleineau lors de ses premi\\u00e8res respirations. \\u00a9 Alex Westover \\\/ Greenpeace&quot;,&quot;focus_image&quot;:&quot;&quot;,&quot;credits&quot;:&quot;&quot;}]}}\"><\/div>\n<h2 class=\"wp-block-heading\"><strong><strong>Pourquoi le gaz naturel est-il nocif ?<\/strong><\/strong><\/h2>\n\n<p>Le gaz naturel comme source d&#8217;\u00e9nergie est consid\u00e9r\u00e9 par beaucoup comme une technologie de transition, car sa combustion produit moins de CO\u2082 que celle du charbon. Pourtant, \u00e0 y regarder de plus pr\u00e8s, le gaz naturel est lui aussi extr\u00eamement nuisible pour le climat. D&#8217;une part, les \u00e9missions de CO\u2082 sont encore bien trop \u00e9lev\u00e9es &#8211; pour prot\u00e9ger le climat, nous avons besoin de z\u00e9ro \u00e9mission. D&#8217;autre part, le gaz naturel est presque enti\u00e8rement compos\u00e9 de m\u00e9thane, un gaz \u00e0 effet de serre beaucoup plus puissant que le CO\u2082. Les \u00e9missions de m\u00e9thane qui s&#8217;\u00e9chappent lors de la production, du transport et de la consommation sont extr\u00eamement nocives pour le climat.\u00a0<\/p>\n\n<p>Le projet de Woodside est d&#8217;exporter le gaz naturel sous forme de gaz liquide dans le monde entier, en abr\u00e9g\u00e9 GNL (gaz naturel liqu\u00e9fi\u00e9). Pour ce faire, le gaz naturel est refroidi \u00e0 -160 degr\u00e9s Celsius au cours d&#8217;un processus tr\u00e8s \u00e9nergivore et ainsi liqu\u00e9fi\u00e9, ce qui r\u00e9duit consid\u00e9rablement son volume. Cela facilite le commerce international : les navires de transport peuvent ainsi acheminer de grandes quantit\u00e9s de gaz naturel, qui sont ensuite regaz\u00e9ifi\u00e9es dans leurs propres terminaux GNL dans le pays d&#8217;arriv\u00e9e. Le bilan climatique de cette infrastructure \u00e9nergivore est toutefois d\u00e9sastreux.<\/p>\n\n<p>Selon les estimations des experts, Scarborough est donc une v\u00e9ritable bombe \u00e0 CO\u2082 : sur une p\u00e9riode allant de 2021 \u00e0 2055, il faut s&#8217;attendre \u00e0 des \u00e9missions de 1370 millions de tonnes d&#8217;\u00e9quivalent CO\u2082 li\u00e9es au projet.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong><strong>Mettre fin \u00e0 la surexploitation, prot\u00e9ger les baleines<\/strong><\/strong><\/h2>\n\n<p>M\u00eame dans le meilleur des cas, ce que Woodside pr\u00e9voit au large des c\u00f4tes est une charge inacceptable pour la vie sous-marine australienne et le climat mondial. Dans un autre rapport intitul\u00e9 &#8220;<a href=\"https:\/\/act.gp\/3OpOawl\">Deep-sea Disaster Why Woodside&#8217;s Burrup Hub project is too risky to proceed<\/a>&#8220;, Greenpeace Autralie et Pacifique met en \u00e9vidence l&#8217;ampleur des risques d&#8217;accident li\u00e9s \u00e0 ce projet. Scarborough et Burrup Hub menacent de d\u00e9truire irr\u00e9m\u00e9diablement des habitatspour des combustibles fossiles que nous ne pouvons plus nous permettre d&#8217;utiliser compte tenu du r\u00e9chauffement de la plan\u00e8te.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd&#8217;hui, des militant\u00b7e\u00b7s Greenpeace Allemagne ont manifest\u00e9 contre le projet de gaz en eaux profondes de l&#8217;entreprise \u00e9nerg\u00e9tique australienne Woodside. Le fournisseur d&#8217;\u00e9nergie allemand RWE veut cofinancer le projet.<\/p>\n","protected":false},"author":89,"featured_media":87510,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_planet4_optimize_post_is_variant":false,"_planet4_optimize_experiment_name":"","_planet4_optimize_variant_name":"","ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"not set","p4_local_project":"not set","p4_basket_name":"not set","p4_department":"","footnotes":""},"categories":[22],"tags":[56],"p4-page-type":[77],"gpch-article-type":[],"class_list":["post-87522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-oceans","p4-page-type-story-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/87522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/comments?post=87522"}],"version-history":[{"count":0,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/87522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/media\/87510"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/media?parent=87522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/categories?post=87522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/tags?post=87522"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/p4-page-type?post=87522"},{"taxonomy":"gpch-article-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/gpch-article-type?post=87522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}