{"id":91199,"date":"2022-11-07T08:02:00","date_gmt":"2022-11-07T07:02:00","guid":{"rendered":"https:\/\/www.greenpeace.ch\/?p=91199"},"modified":"2022-11-08T09:53:14","modified_gmt":"2022-11-08T08:53:14","slug":"cop27-suisse-moins-credible","status":"publish","type":"post","link":"https:\/\/www.greenpeace.ch\/fr\/communique-de-presse\/91199\/cop27-suisse-moins-credible\/","title":{"rendered":"COP 27 : la Suisse de moins en moins cr\u00e9dible"},"content":{"rendered":"\n<p><strong><strong>La Conf\u00e9rence de Charm el-Cheikh de 2022 sur les changements climatiques, ou COP 27, a d\u00e9marr\u00e9 hier en \u00c9gypte.<\/strong> Elle est marqu\u00e9e par l&#8217;ignorance affich\u00e9e par des pays comme la Suisse, qui sont coresponsables du fait qu&#8217;apr\u00e8s 27 conf\u00e9rences des parties, les \u00e9missions qui d\u00e9stabilisent le climat continuent d&#8217;augmenter. Pour que la COP 27 contribue r\u00e9ellement \u00e0 la r\u00e9alisation des objectifs de l&#8217;Accord de Paris, la Suisse et les autres pays riches doivent rompre avec leurs strat\u00e9gies climatiques largement insuffisantes et assumer leurs responsabilit\u00e9s. Ils doivent prendre des engagements concrets et ambitieux sur les questions li\u00e9es au financement de la r\u00e9paration des dommages climatiques et \u00e0 la contribution aux efforts d&#8217;att\u00e9nuation et d&#8217;adaptation. Une d\u00e9l\u00e9gation de Greenpeace sera pr\u00e9sente \u00e0 Charm el-Cheikh afin d&#8217;observer les efforts des gouvernements et de soutenir les initiatives de la soci\u00e9t\u00e9 civile visant \u00e0 prot\u00e9ger les communaut\u00e9s les plus touch\u00e9es.<\/strong><\/p>\n\n<p>&#8220;Malgr\u00e9 les \u00e9pisodes m\u00e9t\u00e9orologiques extr\u00eames particuli\u00e8rement marquants de cette ann\u00e9e, qui ont sem\u00e9 la mort et la destruction, et malgr\u00e9 de r\u00e9centes d\u00e9couvertes qui montrent clairement que des points de basculement climatiques surviendront tr\u00e8s probablement \u00e0 partir d&#8217;un r\u00e9chauffement global de 1,5\u00b0C, la Suisse campe sur des positions largement insuffisantes&#8221;, explique Georg Klingler, expert climat et \u00e9nergie pour Greenpeace Suisse.<\/p>\n\n<p>Les analyses internationales qui comparent les efforts des pays montrent l&#8217;ampleur des carence de la politique climatique suisse :<\/p>\n\n<ul class=\"wp-block-list\"><li>La Suisse n&#8217;a pas tenu ses engagements en mati\u00e8re de protection du climat pour 2020 et n&#8217;est pas mieux plac\u00e9e pour 2030 : si tous les pays s&#8217;alignaient sur les ambitions de la Suisse, la plan\u00e8te se r\u00e9chaufferait de 3\u00b0C par rapport au niveau pr\u00e9industriel. L&#8217;avenir m\u00eame de l&#8217;humanit\u00e9 est ainsi menac\u00e9.<\/li><li>Au lieu d&#8217;une r\u00e9duction de 50% d&#8217;ici 2030, la Suisse doit atteindre au moins 61% par rapport au niveau de 1990. Et ce, sans tenir compte des r\u00e9ductions d&#8217;\u00e9missions r\u00e9alis\u00e9es dans d&#8217;autres pays. De telles r\u00e9ductions doivent s&#8217;ajouter \u00e0 l&#8217;objectif national et permettre de garantir que le bilan des \u00e9missions de gaz \u00e0 effet de serre de la Suisse soit n\u00e9gatif d\u2019ici 2030 par rapport \u00e0 1990.<\/li><li>La r\u00e9gulation des flux financiers reste un \u00e9norme probl\u00e8me. Sept ans apr\u00e8s l&#8217;adoption de l&#8217;accord de Paris, la Suisse ne dispose toujours pas de directives contraignantes pour r\u00e9duire les dommages climatiques dont la place financi\u00e8re et la Banque nationale suisse sont responsables. La place financi\u00e8re suisse se trouve sur une trajectoire allant <a href=\"https:\/\/www.bafu.admin.ch\/bafu\/fr\/home\/themes\/climat\/communiques.msg-id-68482.html\" target=\"_blank\" rel=\"noreferrer noopener\">jusqu&#8217;\u00e0 4\u00b0C de r\u00e9chauffement<\/a>. Cette situation est suicidaire si l&#8217;on consid\u00e8re que la place financi\u00e8re constitue le plus grand levier de la Suisse pour la r\u00e9alisation des objectifs mondiaux de r\u00e9duction des \u00e9missions.<\/li><li>La position de la Suisse pour le financement d&#8217;un d\u00e9veloppement respectueux du climat et la r\u00e9paration des dommages dans les pays qui ont comparativement peu contribu\u00e9 au r\u00e9chauffement par le pass\u00e9 laisse aussi largement \u00e0 d\u00e9sirer. Au lieu de mettre \u00e0 disposition de nouveaux fonds pour r\u00e9soudre le probl\u00e8me et r\u00e9duire les souffrances qui y sont associ\u00e9es, les fonds de la coop\u00e9ration au d\u00e9veloppement sont r\u00e9affect\u00e9s et additionn\u00e9 \u00e0 des cr\u00e9dits priv\u00e9s afin de polir les chiffres.<\/li><\/ul>\n\n<h4 class=\"wp-block-heading\">Greenpeace \u00e0 la COP 27<\/h4>\n\n<p>Une d\u00e9l\u00e9gation internationale de Greenpeace sera pr\u00e9sente sur place \u00e0 Charm el-Cheikh pour la COP 27 et mettra tout en \u0153uvre pour obtenir des avanc\u00e9es en mati\u00e8re de justice climatique (financement des pertes et dommages et de l\u2019adaptation) et d\u2019att\u00e9nuation du r\u00e9chauffement, afin de pr\u00e9server au maximum les chances de limiter le r\u00e9chauffement global \u00e0 1,5\u00b0C. Ses repr\u00e9sentants sont disponibles pour des interviews et des commentaires.<\/p>\n\n<p>Plus d&#8217;informations dans le <a rel=\"noreferrer noopener\" href=\"https:\/\/www.greenpeace.org\/static\/planet4-international-stateless\/2022\/10\/66d9c0b3-greenpeace-cop27-expectations-paper-nov-2022-.pdf\" target=\"_blank\">briefing de Greenpeace International<\/a><\/p>\n\n<h4 class=\"wp-block-heading\">Contacts:<\/h4>\n\n<p>Pour toute question concernant l\u2019\u00e9volution des discussions \u00e0 Charm el-Cheik, merci de contacter directement notre d\u00e9l\u00e9gation sur place en contactant Gaby Flores, charg\u00e9e de communication pour Greenpeace International, pr\u00e9sente \u00e0 Charm El-Cheikh: cflores@greenpeace.org<\/p>\n\n<p>Pour toute question concernant la politique climatique de la Suisse:<\/p>\n\n<p>Georg Klingler, expert climat et \u00e9nergie, Greenpeace Suisse, +41 79 785 07 38, georg.klingler@greenpeace.org<\/p>\n\n<p>Pour toute autre demande:<\/p>\n\n<p>Mathias Schlegel, porte-parole, Greenpeace Suisse, +41 79 794 61 23, mathias.schlegel@greenpeace.org<\/p>\n\n<h4 class=\"wp-block-heading\">Sources :<\/h4>\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/www.pik-potsdam.de\/de\/produkte\/infothek\/kippelemente\/kippelemente\" target=\"_blank\"><br>Etude sur les points de basculement climatiques<\/a><a href=\"https:\/\/climateactiontracker.org\/countries\/switzerland\/\" target=\"_blank\" rel=\"noreferrer noopener\"><br>Analyse des performances de la Suisse par le thinktank Climate Action Tracker<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette conf\u00e9rence est marqu\u00e9e par l&#8217;ignorance affich\u00e9e par des pays comme la Suisse, qui sont coresponsables du fait qu&#8217;apr\u00e8s 27 conf\u00e9rences des parties, les \u00e9missions qui d\u00e9stabilisent le climat continuent d&#8217;augmenter.<\/p>\n","protected":false},"author":37,"featured_media":91201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_planet4_optimize_post_is_variant":false,"_planet4_optimize_experiment_name":"","_planet4_optimize_variant_name":"","ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2022\/11\/a0ce41fe-gp1t2lob_medium_res_with_credit_line.jpg","p4_og_image_id":"91201","p4_seo_canonical_url":"","p4_campaign_name":"not set","p4_local_project":"not set","p4_basket_name":"not set","p4_department":"","footnotes":""},"categories":[22],"tags":[58,136],"p4-page-type":[73],"gpch-article-type":[],"class_list":["post-91199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-climat","tag-justice-climatique","p4-page-type-communique-de-presse"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/91199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/comments?post=91199"}],"version-history":[{"count":0,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/91199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/media\/91201"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/media?parent=91199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/categories?post=91199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/tags?post=91199"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/p4-page-type?post=91199"},{"taxonomy":"gpch-article-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/gpch-article-type?post=91199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}