{"id":98800,"date":"2023-05-25T11:26:06","date_gmt":"2023-05-25T09:26:06","guid":{"rendered":"https:\/\/www.greenpeace.ch\/article-de-magazine\/98800\/die-luegen-der-klimaschwurbler\/"},"modified":"2023-06-07T00:17:20","modified_gmt":"2023-06-06T22:17:20","slug":"les-mensonges-des-conspirationnistes-du-climat","status":"publish","type":"post","link":"https:\/\/www.greenpeace.ch\/fr\/story-fr\/98800\/les-mensonges-des-conspirationnistes-du-climat\/","title":{"rendered":"Les mensonges des conspirationnistes du climat"},"content":{"rendered":"\n<p><em>&#8220;Voulons-nous vraiment nous laisser mettre sous tutelle par des milliardaires am\u00e9ricains ?&#8221;<\/em> m&#8217;a demand\u00e9 ma voisine, inqui\u00e8te, apr\u00e8s avoir rep\u00each\u00e9 dans sa bo\u00eete aux lettres le bulletin A4 du sinistre &#8221; Comit\u00e9 pour le sauvetage de la place industrielle suisse&#8221;.<\/p>\n\n<p>Deux semaines apr\u00e8s le tout m\u00e9nage sp\u00e9cial la loi climat de l&#8217;UDC, un autre flyer s\u00e8me la confusion dans toutes les bo\u00eetes aux lettres de Suisse. La strat\u00e9gie de l&#8217;auteur, Kurt Zollinger, une des voix les plus connues sur le climat au sein de l&#8217;UDC est limpide : <strong>mentir \u00e0 tout va pour d\u00e9stabiliser les citoyens et les faire douter afin de les pousser \u00e0 voter non \u00e0 la loi climat.<\/strong><\/p>\n\n<h2 class=\"wp-block-heading\"><strong><strong>Les affirmations les plus absurdes :<\/strong><\/strong><\/h2>\n\n<ol class=\"wp-block-list\">\n<li><strong>&#8220;Les discours alarmistes&#8221; sur le climat viennent&nbsp; principalement de &#8220;milliardaires am\u00e9ricains&#8221;<br><\/strong><br>Ce serait des milliardaires am\u00e9ricains qui nous interpellent au sujet du r\u00e9chauffement climatique, alors qu\u2019un grand nombre d&#8217;entre eux sont encore fortement investis dans le secteur p\u00e9trolier ? Il y a effectivement quelques&nbsp; grandes fortunes qui souhaitent orienter l&#8217;\u00e9conomie am\u00e9ricaine vers les \u00e9nergies renouvelables et la protection du climat, mais ils sont une minorit\u00e9. Les mises en garde sur le climat viennent le plus souvent du monde scientifique o\u00f9 le consensus sur le sujet est r\u00e9sum\u00e9 et mis en lumi\u00e8re dans les rapports du GIEC. Leurs conclusions sont claires. Ce n&#8217;est que si tous les \u00c9tats du monde s\u2019engagent pour r\u00e9duire les \u00e9missions carbones que nous pourrons nous donner une chance d\u2019\u00e9viter les pires cons\u00e9quences du r\u00e9chauffement de la plan\u00e8te.<\/li>\n\n\n\n<li><strong>&#8220;Des scientifiques s\u00e9rieux et renomm\u00e9s&#8221; estiment que le CO2 a un effet &#8220;\u00e0 peine mesurable sur le climat&#8221;<br><\/strong><br>L\u2019effet du CO2 sur le climat a \u00e9t\u00e9 d\u00e9montr\u00e9 des milliers de fois et document\u00e9 en d\u00e9tail pour la sixi\u00e8me fois dans les rapports du GIEC, qui est le plus grand et le plus complet projet de recherche de l&#8217;histoire de l&#8217;humanit\u00e9 Pourtant Kurt Zollinger, juriste de formation, continue \u00e0 postuler ses mensonges sur le climat. C\u2019est aussi grave que d\u2019affirmer qu\u2019il y a des \u201cscientifiques s\u00e9rieux et renomm\u00e9s\u201d qui estiment que la terre est plate.<\/li>\n<\/ol>\n\n<h2 class=\"wp-block-heading\">Le flyer corrig\u00e9<\/h2>\n\n<p>Nous avons corrig\u00e9 pour vous le vilain flyer de l&#8217;UDC contre la loi climat. Vous pouvez t\u00e9l\u00e9charger ou imprimer le nouveau flyer ci-dessous.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" title=\"2128919f-2023_analyse_werkplatz-schweiz_flyer\" src=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/05\/2128919f-2023_analyse_werkplatz-schweiz_flyer-1024x724.jpg\" alt=\"\" class=\"wp-image-98872\" srcset=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/05\/2128919f-2023_analyse_werkplatz-schweiz_flyer-1024x724.jpg 1024w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/05\/2128919f-2023_analyse_werkplatz-schweiz_flyer-300x212.jpg 300w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/05\/2128919f-2023_analyse_werkplatz-schweiz_flyer-768x543.jpg 768w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/05\/2128919f-2023_analyse_werkplatz-schweiz_flyer-481x340.jpg 481w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/05\/2128919f-2023_analyse_werkplatz-schweiz_flyer.jpg 1121w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">OUI BIEN S\u00dbR que vous pouvez nous aider<\/h2>\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.greenpeace.ch\/fr\/oui-bien-sur\/\"><img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"574\" title=\"Bildschirmfoto 2023-05-26 um 01.09.46\" src=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/05\/54766f3f-bildschirmfoto-2023-05-26-um-01.09.46.png\" alt=\"\" class=\"wp-image-98838\" srcset=\"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/05\/54766f3f-bildschirmfoto-2023-05-26-um-01.09.46.png 870w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/05\/54766f3f-bildschirmfoto-2023-05-26-um-01.09.46-300x198.png 300w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/05\/54766f3f-bildschirmfoto-2023-05-26-um-01.09.46-768x507.png 768w, https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/05\/54766f3f-bildschirmfoto-2023-05-26-um-01.09.46-510x336.png 510w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><\/a><\/figure>\n\n<h2 class=\"wp-block-heading\"><strong><strong>Les autres arguments fallacieux :<\/strong><\/strong><\/h2>\n\n<ol class=\"wp-block-list\" start=\"3\">\n<li><strong>Les co\u00fbts du chauffage et de l\u2019\u00e9lectricit\u00e9 seront nettement plus \u00e9lev\u00e9s, tout comme les loyers et les prix des aliments<br><\/strong><br>Le r\u00e9chauffement climatique entra\u00eene une augmentation des crises, ce qui fait \u00e0 son tour grimper le prix du p\u00e9trole et du gaz. La meilleure fa\u00e7on de se prot\u00e9ger contre des prix \u00e9lev\u00e9s est de produire nous m\u00eame notre \u00e9nergie. Comme nous n&#8217;avons pas de puits de p\u00e9trole en Suisse, nous devrions investir d\u00e8s maintenant dans le d\u00e9veloppement des \u00e9nergies renouvelables afin d&#8217;\u00eatre mieux prot\u00e9g\u00e9s lorsque la prochaine crise surviendra.<br><br>Pour les consommateurs, il n&#8217;y a pas de nouvelles taxes ni de frais suppl\u00e9mentaires. Au contraire, l&#8217;utilisation efficace de l&#8217;\u00e9nergie et l&#8217;augmentation de la production locale d&#8217;\u00e9lectricit\u00e9 r\u00e9duisent les co\u00fbts. La Suisse devient moins d\u00e9pendante des crises internationales. Pour les entreprises, les propri\u00e9taires et, <a rel=\"noreferrer noopener\" href=\"https:\/\/www.energieheld.ch\/heizung\/kosten\" target=\"_blank\">via les frais annexes, les locataires,<\/a> le co\u00fbt de la vie sera mieux ma\u00eetris\u00e9 \u00e0 l&#8217;avenir.<\/li>\n\n\n\n<li><strong>Seuls les plus riches pourront encore avoir une voiture<br><\/strong><br>Aujourd&#8217;hui d\u00e9j\u00e0, l&#8217;\u00e9lectromobilit\u00e9 est plus avantageuse que les v\u00e9hicules \u00e0 combustion, si l&#8217;on consid\u00e8re toute la dur\u00e9e de vie d&#8217;un v\u00e9hicule. Et comme tous les grands constructeurs automobiles passent \u00e0 l&#8217;\u00e9lectrique, les v\u00e9hicules deviennent de moins en moins chers. Pourquoi donc la conduite automobile devrait-elle devenir plus ch\u00e8re ?<\/li>\n\n\n\n<li><strong>L&#8217;industrie suisse ne sera plus comp\u00e9titive<br><\/strong><br>Le passage aux \u00e9nergies renouvelables dans l&#8217;Union europ\u00e9enne est in\u00e9luctable. Et pour prot\u00e9ger l&#8217;\u00e9conomie de l&#8217;UE contre les importations \u00e0 bas prix nuisibles au climat, des droits de douane seront pr\u00e9lev\u00e9s sur les produits qui ne sont pas fabriqu\u00e9s de mani\u00e8re climatiquement compatible. Si notre industrie ne passe pas aux \u00e9nergies renouvelables, elle sera \u00e9galement touch\u00e9e par ces droits de douane. Avec la loi sur la protection du climat, nous soutenons l&#8217;\u00e9conomie dans sa transition et nous lui donnons les moyens de rester comp\u00e9titive.<\/li>\n\n\n\n<li><strong>Des milliers de personnes perdront leur emplois<br><\/strong><br>Au contraire! Si nous ne payons plus 8 \u00e0 10 milliards de CHF par an aux pays producteurs pour notre p\u00e9trole et notre gaz, l&#8217;argent reste en Suisse et cr\u00e9e des emplois ici dans le secteur du solaire, de la construction et ailleurs. Les habitants du pays d\u00e9pensent leur argent ici et cr\u00e9ent des emplois dans le secteur de l&#8217;artisanat et des services.<br><br>Cette corr\u00e9lation est prouv\u00e9e depuis longtemps : <a rel=\"noreferrer noopener\" href=\"https:\/\/digitalcollection.zhaw.ch\/bitstream\/11475\/23240\/3\/2021_ZHAW_Potential-Erneuerbare-Energien-Energieeffizienz.pdf\" target=\"_blank\">une \u00e9tude de la Haute \u00e9cole zurichoise des sciences appliqu\u00e9es (ZHAW) <\/a>chiffre \u00e0 77 milliards de francs d&#8217;ici 2035 le potentiel de cr\u00e9ation de valeur suppl\u00e9mentaire en Suisse en cas de d\u00e9veloppement &#8220;mod\u00e9r\u00e9&#8221; des \u00e9nergies renouvelables et de l&#8217;efficacit\u00e9 \u00e9nerg\u00e9tique. Ce sc\u00e9nario pr\u00e9voit en outre 50 000 emplois suppl\u00e9mentaires, dont plus des deux tiers dans le secteur industriel.<\/li>\n\n\n\n<li><strong>Les mesures contenues dans la loi climat d\u00e9truisent la nature et les paysages<br><\/strong><br>Les glaciers fondent. Le niveau des nappes phr\u00e9atiques baisse. Les agriculteurs luttent contre la s\u00e9cheresse et les inondations. Les h\u00eatres et les \u00e9pic\u00e9as meurent de s\u00e9cheresse et les poissons de la chaleur. Le r\u00e9chauffement climatique d\u00e9truit notre nature et nos paysages.&nbsp;<br><br>Si nous ne parvenons pas \u00e0 ma\u00eetriser le r\u00e9chauffement climatique, nous n&#8217;aurons bient\u00f4t plus de nature et de paysage \u00e0 prot\u00e9ger. En Suisse, il existe depuis longtemps suffisamment de surfaces pouvant \u00eatre utilis\u00e9es pour le d\u00e9veloppement de l&#8217;\u00e9nergie solaire : toitures, fa\u00e7ades, parkings, autoroutes, etc. Si le passage aux \u00e9nergies renouvelables est abord\u00e9 correctement, aucun paysage de valeur ne sera d\u00e9truit.<\/li>\n\n\n\n<li><strong>La loi climat implique des menaces de coupures de courant: les Suisses auront froid en hiver<br><\/strong><br>Gr\u00e2ce aux centrales de pompage-turbinage, la Suisse pourrait s&#8217;approvisionner en \u00e9lectricit\u00e9 de mani\u00e8re autonome pendant deux semaines en hiver, m\u00eame si le soleil ne se levait plus et qu&#8217;il ne tombait pas une goutte de pluie. Mais comme il pleut habituellement en Suisse, ce qui remplit les barrages, ou que le soleil brille et que les panneaux solaires fournissent de l&#8217;\u00e9lectricit\u00e9 m\u00eame par temps couvert, nous ne serons pas confront\u00e9s \u00e0 un sc\u00e9nario aussi extr\u00eame.&nbsp; &#8211; sans m\u00eame compter l&#8217;\u00e9lectricit\u00e9 produite par les centrales hydrauliques au fil de l\u2019eau ou l\u2019\u00e9nergie venue des usines d&#8217;incin\u00e9ration.<br><br>Ajoutons qu\u2019en hiver, le vent souffle particuli\u00e8rement fort en mer du Nord et les pays de l&#8217;UE d\u00e9veloppent massivement la production \u00e9olienne. Certains sc\u00e9narios montrent qu&#8217;il pourrait m\u00eame y avoir plus d&#8217;\u00e9lectricit\u00e9 en hiver qu&#8217;en \u00e9t\u00e9 en Europe. Et en raison d&#8217;hivers de plus en plus chauds, nous avons \u00e9galement besoin de moins en moins d&#8217;\u00e9nergie de chauffage.<\/li>\n\n\n\n<li><strong>Selon &#8220;les calculs de l&#8217;EPFL&#8221;, la loi climat co\u00fbtera pr\u00e8s de 400 milliards de francs<\/strong><strong><br><\/strong><br>Le tout m\u00e9nage mensonger cite ici une \u00e9tude du pire des cas possible pour la Suisse. Tous les sc\u00e9narios r\u00e9alistes des \u00e9coles polytechniques aboutissent \u00e0 des pr\u00e9visions&nbsp; nettement plus avantageuses.<br><br>Selon le DETEC, les investissements dans les centrales \u00e9lectriques, les installations, les g\u00e9n\u00e9rateurs de chaleur, les v\u00e9hicules et les \u00e9l\u00e9ments de construction des b\u00e2timents li\u00e9s \u00e0 l&#8217;\u00e9nergie s&#8217;\u00e9l\u00e8vent au total \u00e0 environ 1400 milliards de francs d&#8217;ici 2050, m\u00eame sans se fixer l\u2019objectif de z\u00e9ro \u00e9mission net.<br><br>Pour atteindre l&#8217;objectif z\u00e9ro net d&#8217;ici 2050, des investissements suppl\u00e9mentaires d&#8217;environ huit pour cent sont n\u00e9cessaires. Si l&#8217;on d\u00e9duit les paiements \u00e9conomis\u00e9s \u00e0 l&#8217;\u00e9tranger pour l&#8217;\u00e9nergie fossile (cf. point 3), il reste environ 5 pour cent, soit 73 milliards de francs. Ces investissements g\u00e9n\u00e9reront \u00e0 leur tour des b\u00e9n\u00e9fices (cf. point 6). Les co\u00fbts suppl\u00e9mentaires pr\u00e9sent\u00e9s par le tout-m\u00e9nage sont donc totalement fantaisistes.<\/li>\n<\/ol>\n\n<p><strong>Il n\u2019y a donc pas lieu de perdre de temps avec de telles fadaises. La corbeille papier est certainement le meilleur endroit o\u00f9 ranger ce document aux affirmations ridicules.&nbsp;<\/strong><\/p>\n\n<h4 class=\"wp-block-heading\">Merci de voter OUI \u00e0 la loi climat le 18 juin prochain, et de faire voter vos proches et vos amis. Plus que jamais, toutes les voix comptent!<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Voulons-nous vraiment nous laisser mettre sous tutelle par des milliardaires am\u00e9ricains ?&#8221; m&#8217;a demand\u00e9 ma voisine, inqui\u00e8te, apr\u00e8s avoir rep\u00each\u00e9 dans sa bo\u00eete aux lettres le bulletin A4 du sinistre &#8221; Comit\u00e9 pour le sauvetage de la place industrielle suisse&#8221;.<\/p>\n","protected":false},"author":112,"featured_media":99019,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_planet4_optimize_post_is_variant":false,"_planet4_optimize_experiment_name":"","_planet4_optimize_variant_name":"","ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"https:\/\/www.greenpeace.ch\/static\/planet4-switzerland-stateless\/2023\/05\/2e03f067-2023_werkplatz-wahrheit_schweiz.pdf-1-1024x724-1.png","p4_og_image_id":"99019","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[112],"tags":[136,58],"p4-page-type":[77],"gpch-article-type":[],"class_list":["post-98800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-klima-fr","tag-justice-climatique","tag-climat","p4-page-type-story-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/98800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/users\/112"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/comments?post=98800"}],"version-history":[{"count":0,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/posts\/98800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/media\/99019"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/media?parent=98800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/categories?post=98800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/tags?post=98800"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/p4-page-type?post=98800"},{"taxonomy":"gpch-article-type","embeddable":true,"href":"https:\/\/www.greenpeace.ch\/fr\/wp-json\/wp\/v2\/gpch-article-type?post=98800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}